{"id":2522,"date":"2020-01-23T08:00:00","date_gmt":"2020-01-23T12:00:00","guid":{"rendered":"https:\/\/venfort.com\/blog\/?p=1096"},"modified":"2020-01-23T08:00:00","modified_gmt":"2020-01-23T12:00:00","slug":"prueba-indiciaria-aliada-para-construccion-judicial","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/prueba-indiciaria-aliada-para-construccion-judicial\/","title":{"rendered":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>En la construcci\u00f3n de los casos jur\u00eddicos, existen elementos de los que no se encuentran pruebas que puedan comprobar de forma directa su ocurrencia. En esas oportunidades, la prueba indiciaria \u2014tambi\u00e9n conocida como prueba indirecta\u2014 entra en juego para apoyar el proceso, pues permite acreditar esos hechos que no est\u00e1n avalados por pruebas directas. Para ello, las pruebas indirectas conducen a la deducci\u00f3n razonable o inferencia de la ocurrencia de ciertos eventos, a trav\u00e9s de estimaciones probadas de otros hechos relacionados que s\u00ed han sido probados directamente.<\/p><\/blockquote>\n\n\n\n<p><strong>La prueba indiciaria o indirecta, solo tiene sentido cuando es empleada a partir de un hecho ya admitido<\/strong> o probado que pueda dar indicio a la presunci\u00f3n de una certeza a los efectos del proceso jur\u00eddico, es decir, debe contener suficiente informaci\u00f3n y estar vinculada de forma directa con las otras pruebas que ya han sido comprobadas y correlacionadas al caso.<\/p>\n\n\n\n<p><strong>Sin embargo, el alcance de este tipo de pruebas es limitado pues no es v\u00e1lida cuando falte un enlace preciso<\/strong> y directo entre el hecho base y el hecho deducido. Adem\u00e1s, hay que tomar en cuenta que la prueba indirecta no necesariamente conlleva a un resultado \u00fanico, sino que es posible que admite diversas opciones l\u00f3gicas provenientes de los mismos hechos tomados como base.<\/p>\n\n\n\n<p><strong>No es f\u00e1cil reconocer la validez de una prueba indiciaria <a href=\"https:\/\/venfort.com\/blog\/derecho-a-la-defensa-garantia-debido-proceso\/\">en un proceso legal<\/a>.<\/strong> En ella el objeto de la prueba es un hecho diferente del que debe ser probado y con relevancia jur\u00eddica frente al caso. En ese sentido, la relaci\u00f3n de los hechos probados permite alcanzar el hecho a probar, gracias al juicio de inferencia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El Tribunal Supremo de Espa\u00f1a reconoce 19 criterios para validar el uso de las pruebas indiciarias o indirectas:<\/h2>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Deben tratarse de indicios probados<\/strong>: Los indicios son diferentes a las sospechas, para incluir una de estas pruebas es necesario contar con indicios probados y no con meras posibilidades.<\/li><li><strong>No se debe fundamentar <\/strong>una sentencia en el convencimiento subjetivo.<\/li><li><strong>Se debe estar convencido<\/strong> de que los hechos ocurrieron como se relatan.<\/li><li><strong>Se debe motivar la concurrencia<\/strong> de indicios y su relevancia probatoria.<\/li><li><strong>Los elementos para una prueba indiciaria<\/strong> son los siguientes: Una afirmaci\u00f3n base o de indicio, una afirmaci\u00f3n consecuencia (la referencia en la sentencia de lo que se deduce) y un enlace l\u00f3gico y racional entre los dos elementos.\u00a0<\/li><li><strong>Los requisitos para una prueba indiciaria son<\/strong> los siguientes: a) Pluralidad de indicios, b) Demostraci\u00f3n mediante prueba directa de la pluralidad de indicios, c) Enlace preciso, concreto y directo seg\u00fan las reglas del criterio humano entre el hecho demostrado o indicio y el que se trate de deducir, d) Que el \u00f3rgano judicial motive en su sentencia el razonamiento de c\u00f3mo ha llegado a la certeza del hecho.<\/li><li><strong>La exigencia de la motivaci\u00f3n<\/strong> y explicaci\u00f3n del caso debe ser m\u00e1s fuerte y precisa en torno a la prueba indiciaria que en la prueba directa.<\/li><li><strong>Debe haber un razonamiento<\/strong> inductivo propia de la prueba de indicios.<\/li><li><strong>La motivaci\u00f3n es indispensable<\/strong> para el proceso de inferencia de indicios.<\/li><li><strong>El enlace l\u00f3gico entre el indicio y la afirmaci\u00f3n<\/strong> priva en el \u00e9xito de la presentaci\u00f3n de este tipo de pruebas.<\/li><li><strong>Exigen la llamada certeza subjetiva<\/strong>, que conduce a la convicci\u00f3n judicial.<\/li><li><strong>La suma de indicios<\/strong> determina que se cometi\u00f3 el delito.<\/li><li><strong>Requiere constatar unos hechos<\/strong> mediatos para concluir hechos inmediatos.<\/li><li><strong>El juicio de inferencia<\/strong> debe quedar suficientemente claro.<\/li><li><strong>Todo el proceso de inferencia<\/strong> tiene que ser razonable.<\/li><li><strong>Los indicios<\/strong> deben formar una cadena.<\/li><li><strong>Debe poder efectuarse el control<\/strong> de constitucionalidad.<\/li><li><strong>La conclusi\u00f3n de una inferencia<\/strong> presuntiva debe considerarse cerrada, fuerte y determinada.<\/li><li><strong>Debe exigirse<\/strong> una probabilidad prevaleciente.<\/li><\/ol>\n\n\n\n<h4 class=\"has-text-align-center wp-block-heading\">En Alan Aldana &amp; Abogados, contamos con un equipo de expertos especializados en el \u00e1rea de pruebas quienes son los encargados del estudio de un caso concreto a los fines que nuestros representados consigan los objetivos requeridos en un juicio.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>En la construcci\u00f3n de los casos jur\u00eddicos, existen elementos de los que no se encuentran pruebas que puedan comprobar de forma directa su ocurrencia. En esas oportunidades, la prueba indiciaria \u2014tambi\u00e9n conocida como prueba indirecta\u2014 entra en juego para apoyar el proceso, pues permite acreditar esos hechos que no est\u00e1n avalados por pruebas directas. Para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[29],"tags":[125,241],"class_list":["post-2522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ejercicio-profesional","tag-espana","tag-legalidad","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La prueba indiciaria, una aliada para la construcci\u00f3n judicial<\/title>\n<meta name=\"description\" content=\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial. En este art\u00edculo compartimos el concepto y lo que implica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/prueba-indiciaria-aliada-para-construccion-judicial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial\" \/>\n<meta property=\"og:description\" content=\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial. En este art\u00edculo compartimos el concepto y lo que implica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/prueba-indiciaria-aliada-para-construccion-judicial\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-23T12:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/prueba-indiciaria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial\",\"datePublished\":\"2020-01-23T12:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/\"},\"wordCount\":681,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/prueba-indiciaria.jpg\",\"keywords\":[\"Espa\u00f1a\",\"Legalidad\"],\"articleSection\":[\"Ejercicio Profesional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/\",\"name\":\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/prueba-indiciaria.jpg\",\"datePublished\":\"2020-01-23T12:00:00+00:00\",\"description\":\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial. En este art\u00edculo compartimos el concepto y lo que implica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/prueba-indiciaria.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/prueba-indiciaria.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/prueba-indiciaria-aliada-para-construccion-judicial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La prueba indiciaria, una aliada para la construcci\u00f3n judicial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial","description":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial. En este art\u00edculo compartimos el concepto y lo que implica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/prueba-indiciaria-aliada-para-construccion-judicial\/","og_locale":"es_ES","og_type":"article","og_title":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial","og_description":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial. En este art\u00edculo compartimos el concepto y lo que implica.","og_url":"https:\/\/venfort.com\/es\/prueba-indiciaria-aliada-para-construccion-judicial\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2020-01-23T12:00:00+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/prueba-indiciaria.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial","datePublished":"2020-01-23T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/"},"wordCount":681,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/prueba-indiciaria.jpg","keywords":["Espa\u00f1a","Legalidad"],"articleSection":["Ejercicio Profesional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/","url":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/","name":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/prueba-indiciaria.jpg","datePublished":"2020-01-23T12:00:00+00:00","description":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial. En este art\u00edculo compartimos el concepto y lo que implica.","breadcrumb":{"@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/prueba-indiciaria.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/prueba-indiciaria.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/prueba-indiciaria-aliada-para-construccion-judicial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"La prueba indiciaria, una aliada para la construcci\u00f3n judicial"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2522"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2523"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}