{"id":2542,"date":"2019-10-24T08:00:17","date_gmt":"2019-10-24T12:00:17","guid":{"rendered":"https:\/\/venfort.com\/?p=1055"},"modified":"2019-10-24T08:00:17","modified_gmt":"2019-10-24T12:00:17","slug":"defensa-de-meng-wanzhou","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/defensa-de-meng-wanzhou\/","title":{"rendered":"Defensa de Meng Wanzhou juega nueva variable en caso de extradici\u00f3n a Estados Unidos"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La revisi\u00f3n de las entrevistas realizadas a Meng Wanzhou, durante su retenci\u00f3n en Canad\u00e1, abrieron un nuevo camino a la defensa de la directora financiera de Huawei, a qui\u00e9n se le ha imputado (junto a la compa\u00f1\u00eda tecnol\u00f3gica) <a href=\"https:\/\/venfort.com\/huawei-cargos-legales\/#.Xat4ZuhKgdU\">de al menos 24 cargos interpuestos por Estados Unidos<\/a>, entre los que figuran delitos de fraude, conspiraci\u00f3n y obstrucci\u00f3n de la justicia, relacionados con un supuesto plan para eludir las sanciones del pa\u00eds de norteam\u00e9rica contra Ir\u00e1n.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En septiembre, los abogados de Wanzhou solicitaron el acceso a los documentos del registro de la detenci\u00f3n<\/strong> inicial de su clienta en el aeropuerto de Vancouver (Canad\u00e1) durante diciembre de 2018, tras la orden de extradici\u00f3n fijada por Estados Unidos. Como parte de los argumentos presentados recientemente, la defensa asegura que el gobierno del presidente Donald Trump, est\u00e1 usando el caso para obtener ganancias econ\u00f3micas y pol\u00edticas, frente al conflicto que mantiene con China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La evidencia que se est\u00e1 investigando actualmente sugiere que cuando Meng fue interrogada al momento del arresto<\/strong> sobre los negocios del gigante chino con Ir\u00e1n, la directora de Huawei neg\u00f3 tener informaci\u00f3n sobre si los productos de la marca se comercializaban en pa\u00edses donde era prohibido hacerlo y mencion\u00f3 que la compa\u00f1\u00eda tiene una oficina en Ir\u00e1n. Estas declaraciones podr\u00edan abonar el camino para hacer retroceder la extradici\u00f3n, pues apoyan la tesis que sugiere que la acusada fue enga\u00f1ada sobre el prop\u00f3sito de su detenci\u00f3n, violando su derecho fundamental de ser informada sobre los hechos espec\u00edficos que generaron su detenci\u00f3n, lo cual le gener\u00f3 una clara violaci\u00f3n a su derecho de defensa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los argumentos de la defensa de Meng Wanzhou<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hasta el momento, Meng y sus abogados han negado todos los cargos presentados<\/strong> en contra de ella y de Huawei. La nueva clave de la defensa implica una demanda civil que se trata de un procedimiento judicial diferente al de la extradici\u00f3n. Sin embargo, ambos se relacionan y se enfocar\u00e1n en las razones que condujeron al arresto de Meng.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La audiencia de extradici\u00f3n est\u00e1 programada para iniciar en enero del pr\u00f3ximo a\u00f1o, 2020<\/strong>. Mientras tanto, las relaciones entre Canad\u00e1 y China parecen complicarse cada d\u00eda m\u00e1s. El gobierno chino bloque\u00f3 las importaciones de semilla de canola, carne de cerdo y de res de Canad\u00e1. De igual manera, dos canadienses acusados de narcotr\u00e1fico fueron condenados a muerte al ser arrestados en China dos d\u00edas despu\u00e9s de la detenci\u00f3n de la directora financiera de la compa\u00f1\u00eda tecnol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En agosto de este a\u00f1o, Estados Unidos y China se hab\u00edan dado una tregua <\/strong>tras el encuentro de ambos mandatarios en la Cumbre del G20. En ese momento hab\u00edan acordado reanudar las negociaciones comerciales paralizadas, lo que significaba que las empresas norteamericanas pod\u00edan volver a vender partes y equipos de Huawei.\u00a0<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" style=\"text-align:center\">Los especialistas de derecho penal internacional de Alan Aldana &amp; Abogados, consideran que la defensa de la ciudadana Meng Wanzhou en caso de salir desfavorecida en el pronunciamiento del juzgado Canadiense, est\u00e1n en el derecho de realizar una denuncia ante el comit\u00e9 de Derechos Humanos de Naciones Unidas a los fines que sea revisado un proceso judicial que se ha visto empa\u00f1ado por conflictos geopol\u00edticos.<\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">Fuentes:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\"cbc.ca (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.cbc.ca\/news\/canada\/british-columbia\/meng-wanzhou-september-hearing-1.5289143\" target=\"_blank\">cbc.ca<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"burnabynow.com (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.burnabynow.com\/next-steps-in-meng-wanzhou-legal-proceedings-to-kick-off-monday-1.23953561\" target=\"_blank\">burnabynow.com<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"elpais.com (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/elpais.com\/elpais\/2019\/09\/25\/gente\/1569425016_434039.html\" target=\"_blank\">elpais.com<\/a><\/li><li><a href=\"https:\/\/mundo.sputniknews.com\/politica\/201908221088449347-el-caso-de-la-princesa-de-huawei-detenida-en-canada-da-un-nuevo-giro-de-timon\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"mundo.sputniknews.com (abre en una nueva pesta\u00f1a)\">mundo.sputniknews.com<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La revisi\u00f3n de las entrevistas realizadas a Meng Wanzhou, durante su retenci\u00f3n en Canad\u00e1, abrieron un nuevo camino a la defensa de la directora financiera de Huawei, a qui\u00e9n se le ha imputado (junto a la compa\u00f1\u00eda tecnol\u00f3gica) de al menos 24 cargos interpuestos por Estados Unidos, entre los que figuran delitos de fraude, conspiraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2543,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[29],"tags":[65,121],"class_list":["post-2542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ejercicio-profesional","tag-derecho-mercantil","tag-huawei","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Defensa de Meng Wanzhou se prepara en caso de extradici\u00f3n a EEUU<\/title>\n<meta name=\"description\" content=\"De momento, la defensa de Meng Wanzhou han negado todos los cargos presentados en contra de ella y de Huawei. Podr\u00eda haber una demanda civil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/defensa-de-meng-wanzhou\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Defensa de Meng Wanzhou se prepara en caso de extradici\u00f3n a EEUU\" \/>\n<meta property=\"og:description\" content=\"De momento, la defensa de Meng Wanzhou han negado todos los cargos presentados en contra de ella y de Huawei. Podr\u00eda haber una demanda civil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/defensa-de-meng-wanzhou\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-24T12:00:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2019\/10\/defensa-meng-wanzhou.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"Defensa de Meng Wanzhou juega nueva variable en caso de extradici\u00f3n a Estados Unidos\",\"datePublished\":\"2019-10-24T12:00:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/\"},\"wordCount\":589,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/defensa-meng-wanzhou.jpg\",\"keywords\":[\"Derecho Mercantil\",\"Huawei\"],\"articleSection\":[\"Ejercicio Profesional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/\",\"name\":\"Defensa de Meng Wanzhou se prepara en caso de extradici\u00f3n a EEUU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/defensa-meng-wanzhou.jpg\",\"datePublished\":\"2019-10-24T12:00:17+00:00\",\"description\":\"De momento, la defensa de Meng Wanzhou han negado todos los cargos presentados en contra de ella y de Huawei. Podr\u00eda haber una demanda civil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/defensa-meng-wanzhou.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/defensa-meng-wanzhou.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/defensa-de-meng-wanzhou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Defensa de Meng Wanzhou juega nueva variable en caso de extradici\u00f3n a Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Defensa de Meng Wanzhou se prepara en caso de extradici\u00f3n a EEUU","description":"De momento, la defensa de Meng Wanzhou han negado todos los cargos presentados en contra de ella y de Huawei. Podr\u00eda haber una demanda civil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/defensa-de-meng-wanzhou\/","og_locale":"es_ES","og_type":"article","og_title":"Defensa de Meng Wanzhou se prepara en caso de extradici\u00f3n a EEUU","og_description":"De momento, la defensa de Meng Wanzhou han negado todos los cargos presentados en contra de ella y de Huawei. Podr\u00eda haber una demanda civil.","og_url":"https:\/\/venfort.com\/es\/defensa-de-meng-wanzhou\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2019-10-24T12:00:17+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/10\/defensa-meng-wanzhou.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"Defensa de Meng Wanzhou juega nueva variable en caso de extradici\u00f3n a Estados Unidos","datePublished":"2019-10-24T12:00:17+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/"},"wordCount":589,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/10\/defensa-meng-wanzhou.jpg","keywords":["Derecho Mercantil","Huawei"],"articleSection":["Ejercicio Profesional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/","url":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/","name":"Defensa de Meng Wanzhou se prepara en caso de extradici\u00f3n a EEUU","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/10\/defensa-meng-wanzhou.jpg","datePublished":"2019-10-24T12:00:17+00:00","description":"De momento, la defensa de Meng Wanzhou han negado todos los cargos presentados en contra de ella y de Huawei. Podr\u00eda haber una demanda civil.","breadcrumb":{"@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/defensa-de-meng-wanzhou\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/10\/defensa-meng-wanzhou.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/10\/defensa-meng-wanzhou.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/defensa-de-meng-wanzhou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"Defensa de Meng Wanzhou juega nueva variable en caso de extradici\u00f3n a Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2543"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}