{"id":2566,"date":"2019-08-22T20:02:32","date_gmt":"2019-08-23T00:02:32","guid":{"rendered":"https:\/\/venfort.com\/?p=1006"},"modified":"2019-08-22T20:02:32","modified_gmt":"2019-08-23T00:02:32","slug":"ex-presidente-alejandro-toledo-extradicion","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/ex-presidente-alejandro-toledo-extradicion\/","title":{"rendered":"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso que todav\u00eda espera respuesta"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial debido a la acusaci\u00f3n de delitos de <a href=\"https:\/\/venfort.com\/legitimacion-de-capitales-riesgo\/#.XVCW1ehKgdU\">malversaci\u00f3n de fondos y blanqueo de capitales<\/a> que pesaba en su contra, tras su periodo presidencial de 2001 a 2006.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La orden de detenci\u00f3n fue ejecutada por la acusaci\u00f3n de recibir m\u00e1s de 20 millones de d\u00f3lares en sobornos<\/strong> de la constructora brasile\u00f1a Odebrecht. Toledo, resid\u00eda en Estados Unidos cuando fue notificado de las medidas judiciales, por ello en mayo de 2018 el gobierno de Per\u00fa solicit\u00f3 su extradici\u00f3n al pa\u00eds norteamericano. El Ministerio P\u00fablico peruano determin\u00f3 en su investigaci\u00f3n que podr\u00eda estar sujeto a la suma de penas por concurso real de delitos de 16 a\u00f1os y ocho meses de prisi\u00f3n.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/venfort.com\/proceso-de-extradicion\/#.XVFNLehKgdU\"><strong>La extradici\u00f3n es un proceso judicial<\/strong><\/a><strong> a trav\u00e9s del cual un Estado hace la petici\u00f3n de devoluci\u00f3n de un imputado<\/strong> por un delito que se encuentra en otro pa\u00eds, y frente a quien se le ha emitido una orden de detenci\u00f3n internacional, con la intenci\u00f3n de enjuiciarlo en el pa\u00eds requirente. Se encuentra regulada por tratados internacionales y en las leyes de cada pa\u00eds, pues para que sea efectiva se necesita de la firma de convenios internacionales que amparan esta figura entre las naciones involucradas. Per\u00fa y Estados Unidos forman parte de los pa\u00edses que han formalizado su participaci\u00f3n en estos convenios de car\u00e1cter internacional. Sin embargo, en el caso de que no exista este acuerdo previo, el Estado puede ejecutar la extradici\u00f3n pero no est\u00e1 obligado a realizarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El 19 de julio de 2019 el juez Thomas Hixson del tribunal en San Francisco<\/strong>, experto en propiedad intelectual y derecho de competencia, determin\u00f3 que Toledo deb\u00eda enfrentar la extradici\u00f3n en condici\u00f3n de detenido. El pedido tuvo raz\u00f3n de ser como medida para prevenir cualquier intento de fuga o de evasi\u00f3n de la justicia en este proceso de extradici\u00f3n, aprobando la solicitud del bufete de abogados estadounidense contratado por el gobierno peruano.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En esa misma audiencia del mes de julio<\/strong>, la defensa del ex mandatario solicit\u00f3 la asignaci\u00f3n de un abogado p\u00fablico, propuesta que se program\u00f3 para ser evaluada el 22 de agosto de este a\u00f1o ante el mismo tribunal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los hechos en el caso del ex presidente Alejandro Toledo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En el caso se ha contado con la colaboraci\u00f3n de confesi\u00f3n del testaferro principal<\/strong> del acusado, el empresario\u00a0peruano &#8211; israel\u00ed Josef Mainman quien asegur\u00f3 haber recibido (por petici\u00f3n de Toledo) dep\u00f3sitos de m\u00e1s de 21 millones de d\u00f3lares de las empresas Odebrecht y Camargo Correa a cambio de la concesi\u00f3n de obras de construcci\u00f3n de infraestructura vial en Per\u00fa. Pero cuya admisi\u00f3n de hechos o colaboraci\u00f3n debe ser analizada con profundidad antes de darle pleno valor probatorio, ya que podr\u00eda estar viciada de nulidad.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los ex presidentes peruanos que han ocupado el cargo desde 2001 han sido investigados<\/strong> por delitos relacionados al caso Odebrecht. Ollanta Humala fue sentenciado a 20 a\u00f1os de prisi\u00f3n por los actos de corrupci\u00f3n, mientras que a Alan Garc\u00eda le fue entregada una orden de prisi\u00f3n preliminar por su acci\u00f3n en lavado de activos, colusi\u00f3n y tr\u00e1fico de influencia, condena que no pudo ser materializada por el suicidio del ex mandatario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para culminar, en Alan Aldana &amp; Abogados, consideramos que estos casos de relevancia <\/strong>donde se observan indicios de influencia pol\u00edtica, generan en la opini\u00f3n p\u00fablica los denominados juicios paralelos. Los cuales indudablemente permean a los responsables de las investigaciones y a los jueces percepciones que pueden estar alejadas del razonamiento jur\u00eddico que se debe aplicar al caso en concreto. Por eso, adem\u00e1s de enaltecer la total independencia de las decisiones de \u00f3rganos jurisdiccionales, para este tipo de casos nuestra firma aconseja trabajar con expertos en materia de comunicaci\u00f3n estrat\u00e9gica que apoyen al equipo de defensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes consultadas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\"elpais.es (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/elpais.com\/internacional\/2019\/07\/16\/america\/1563303795_244214.html\" target=\"_blank\">elpais.es<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"cnnenespanol.com (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/cnnespanol.cnn.com\/2019\/07\/19\/alerta-san-francisco-alejandro-toledo-seguira-detenido-en-una-carcel-de-california\/\" target=\"_blank\">cnnenespanol.com<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"larepublica.pe (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/larepublica.pe\/politica\/2019\/07\/21\/de-la-lucha-contra-el-fujimorismo-a-la-prision-por-corrupcion\/\" target=\"_blank\">larepublica.pe<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"elcomercio.pe (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/elcomercio.pe\/politica\/alejandro-toledo-ilustradora-dibujo-audiencia-habia-expresion-rostro-noticia-nndc-657193\" target=\"_blank\">elcomercio.pe<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"telemundo31.com (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.telemundo31.com\/videos\/noticias\/arrestan-a-expresidente-de-peru-alejandro-toledo-512824602.html\" target=\"_blank\">telemundo31.com<\/a><\/li><li><a href=\"https:\/\/peru21.pe\/politica\/alejandro-toledo-hoy-define-expresidente-accede-defensa-publica-494826\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"peru21.pe (abre en una nueva pesta\u00f1a)\">peru21.pe<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial debido a la acusaci\u00f3n de delitos de malversaci\u00f3n de fondos y blanqueo de capitales que pesaba en su contra, tras su periodo presidencial de 2001 a 2006. La orden de detenci\u00f3n fue ejecutada por la acusaci\u00f3n de recibir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2567,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[25],"tags":[159,119],"class_list":["post-2566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jurisdiccion-internacional","tag-alejandro-toledo","tag-extradicion","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso en espera<\/title>\n<meta name=\"description\" content=\"A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial vinculado a blanqueo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/ex-presidente-alejandro-toledo-extradicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso en espera\" \/>\n<meta property=\"og:description\" content=\"A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial vinculado a blanqueo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/ex-presidente-alejandro-toledo-extradicion\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-23T00:02:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2019\/08\/presidente-alejandro-toledo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso que todav\u00eda espera respuesta\",\"datePublished\":\"2019-08-23T00:02:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/\"},\"wordCount\":707,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/presidente-alejandro-toledo.jpg\",\"keywords\":[\"Alejandro Toledo\",\"Extradici\u00f3n\"],\"articleSection\":[\"Jurisdicci\u00f3n Internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/\",\"name\":\"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso en espera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/presidente-alejandro-toledo.jpg\",\"datePublished\":\"2019-08-23T00:02:32+00:00\",\"description\":\"A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial vinculado a blanqueo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/presidente-alejandro-toledo.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/presidente-alejandro-toledo.jpg\",\"width\":1024,\"height\":588,\"caption\":\"Foto: Canal N.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/ex-presidente-alejandro-toledo-extradicion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso que todav\u00eda espera respuesta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso en espera","description":"A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial vinculado a blanqueo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/ex-presidente-alejandro-toledo-extradicion\/","og_locale":"es_ES","og_type":"article","og_title":"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso en espera","og_description":"A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial vinculado a blanqueo.","og_url":"https:\/\/venfort.com\/es\/ex-presidente-alejandro-toledo-extradicion\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2019-08-23T00:02:32+00:00","og_image":[{"width":1024,"height":588,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/08\/presidente-alejandro-toledo.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso que todav\u00eda espera respuesta","datePublished":"2019-08-23T00:02:32+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/"},"wordCount":707,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/08\/presidente-alejandro-toledo.jpg","keywords":["Alejandro Toledo","Extradici\u00f3n"],"articleSection":["Jurisdicci\u00f3n Internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/","url":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/","name":"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso en espera","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/08\/presidente-alejandro-toledo.jpg","datePublished":"2019-08-23T00:02:32+00:00","description":"A comienzos del a\u00f1o 2017 el ex presidente peruano Alejandro Toledo, comenz\u00f3 a atravesar un proceso judicial vinculado a blanqueo.","breadcrumb":{"@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/08\/presidente-alejandro-toledo.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/08\/presidente-alejandro-toledo.jpg","width":1024,"height":588,"caption":"Foto: Canal N."},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/ex-presidente-alejandro-toledo-extradicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"La extradici\u00f3n del ex presidente Alejandro Toledo: un proceso que todav\u00eda espera respuesta"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2566"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2567"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}