{"id":2610,"date":"2019-03-21T08:00:14","date_gmt":"2019-03-21T12:00:14","guid":{"rendered":"https:\/\/venfort.com\/?p=898"},"modified":"2019-03-21T08:00:14","modified_gmt":"2019-03-21T12:00:14","slug":"el-interrogatorio-en-derecho","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/el-interrogatorio-en-derecho\/","title":{"rendered":"La credibilidad en el interrogatorio, un valor a construir en Derecho"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Dejar que la verdad sea la que gu\u00ede cada una de las acciones profesionales es la forma m\u00e1s honesta y la \u00fanica posibilidad real de construir la credibilidad, sobre todo cuando se trabaja en espacios donde la palabra es fundamental, como en el mundo del Derecho. El abogado litigante asume la responsabilidad ante un juzgado y testigos de llevar a buen t\u00e9rmino la defensa de su cliente. Cuando esta actividad profesional se desarrolla atendiendo a la \u00e9tica y la moralidad, la preparaci\u00f3n de preguntas para el interrogatorio de testigos se hace de forma hilada y r\u00e1pida, sin dejar ning\u00fan cabo suelto.<br><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los interrogatorios para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante <\/strong>en el litigio y por lo tanto, <a href=\"https:\/\/venfort.com\/abogado-penalista-proceso-judicial\/\">el abogado debe ser cauteloso<\/a> en la selecci\u00f3n de las preguntas y en la forma en la que estas son elaboradas. Las preguntas siempre deben ser claras, precisas y concisas, con la intenci\u00f3n de que el interlocutor sea capaz de comprender cabalmente el cuestionamiento y que ninguna de las palabras se preste a malas interpretaciones. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Una vez que el abogado comprende que la veracidad y honestidad son las piezas claves en la construcci\u00f3n de la credibilidad de los testigos, las siguientes recomendaciones contribuyen a lograrlo lograrlo de forma m\u00e1s r\u00e1pida y \u00f3ptima:<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><strong>Antes de incluir a un testigo que forme parte de los argumentos que defienden la causa<\/strong>, el profesional debe considerar la pertinencia de su testimonio para esclarecer los hechos y aportar datos de inter\u00e9s a la defensa. Estos aspectos deben estar claramente estudiados y evaluados previamente.<\/li><li><strong>El interrogatorio s\u00f3lo funciona cuando se tiene un objetivo definido<\/strong>. No tiene validez salir a pescar en el cuestionamiento pues la defensa podr\u00eca verse severamente afectada en estos casos.<\/li><li><strong>Las primeras preguntas realizadas al testigo deben por tanto aclarar dudas<\/strong> sobre su procedencia y generar confianza en el juzgado. Es decir, el abogado deber\u00e1 hacer cuestionamiento que validan la importancia de su testigo para el caso. Esto es imposible si el profesional no lo tiene completamente claro dentro s\u00ed.<\/li><li><strong>Como se dijo anteriormente, las primeras preguntas est\u00e1n enfocadas en la presentaci\u00f3n del testigo<\/strong>. Es importante destacar que no es necesario incluir en el di\u00e1logo datos que no aporten informaci\u00f3n de relevancia. Estas preguntas iniciales tambi\u00e9n generar\u00e1n confianza entre el abogado y su testigo.<\/li><li><strong>Como parte de la presentaci\u00f3n del testigo, es vital incluir preguntas donde se demuestre<\/strong> la no vinculaci\u00f3n del testigo con las personas comprometidas en el caso, lo que determinar\u00e1 el conflicto de intereses que puedan generarse. El abogado deber\u00e1 estar atento a a este punto, con la intenci\u00f3n de mantener la claridad en todo momento, negar informaci\u00f3n es contraproducente para el caso.<\/li><li><strong>Una vez finalizada la presentaci\u00f3n, se proceder\u00e1 con la bater\u00eda de preguntas destinadas<\/strong> a profundizar en el testimonio por el cual la persona fue llamada al proceso jur\u00eddico. En esta etapa es crucial comprender que la confianza del testigo tambi\u00e9n se construye con base en el conocimiento personal que este tenga sobre los hechos, las circunstancias desde donde pudo registrarlos, su memoria, sus capacidades retentivas y expresivas, e incluso los aspectos que le otorguen objetividad en la narraci\u00f3n.<\/li><li><strong>Toda la informaci\u00f3n recabada antes del interrogatorio a sus testigo<\/strong> y posterior a este evento debe ser lo suficientemente \u00f3ptima para generar l\u00edneas de defensa s\u00f3lidas para el caso. Es una habilidad profesional del abogado saber aprovechar con profesionalismo y \u00e9tica esta herramienta del litigio.<\/li><li><strong>Al obtener la informaci\u00f3n deseada en un interrogatorio lo m\u00e1s prudente es cesar el interrogatorio<\/strong>. En oportunidades, introducir nuevas piezas en el juego puede complicar a la defensa.<\/li><li><strong>Si el abogado no conoce la respuesta<\/strong> es mejor que no se arriesgue a formular la pregunta.<\/li><li><strong>Ante cualquier respuesta fuera del gui\u00f3n establecido<\/strong>, o ante un testigo que miente es importante que el profesional no pierda el equilibrio y que demuestre manejar todas las opciones que se presentan.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:center\">En ALAN ALDANA &amp; ABOGADOS, siempre recordamos que es mejor tener un testigo bueno que uno y medio\u2026.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Fuentes consultadas<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\"legaltoday.com (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.legaltoday.com\/blogs\/gestion-del-despacho\/blog-manual-interno-de-gestion\/como-interrogar-para-acreditar-el-testimonio-de-nuestro-testigo\" target=\"_blank\">legaltoday.com<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"abogacia.es (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.abogacia.es\/2019\/01\/29\/siete-maximas-para-interrogar-a-un-testigo-hostil\/\" target=\"_blank\">abogacia.es<\/a><\/li><li><a href=\"http:\/\/www.legaltoday.com\/blogs\/gestion-del-despacho\/blog-manual-interno-de-gestion\/como-comenzar-el-interrogatorio-directo-de-un-testigo\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"legaltoday.com (abre en una nueva pesta\u00f1a)\">legaltoday.com<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dejar que la verdad sea la que gu\u00ede cada una de las acciones profesionales es la forma m\u00e1s honesta y la \u00fanica posibilidad real de construir la credibilidad, sobre todo cuando se trabaja en espacios donde la palabra es fundamental, como en el mundo del Derecho. El abogado litigante asume la responsabilidad ante un juzgado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2611,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[29],"tags":[79,323,325],"class_list":["post-2610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ejercicio-profesional","tag-derecho-penal","tag-interrogatorio","tag-testigos","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La credibilidad en el interrogatorio, un valor a construir en Derecho<\/title>\n<meta name=\"description\" content=\"El interrogatorio para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante en el ejercicio legal. De eso va este post.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/el-interrogatorio-en-derecho\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La credibilidad en el interrogatorio, un valor a construir en Derecho\" \/>\n<meta property=\"og:description\" content=\"El interrogatorio para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante en el ejercicio legal. De eso va este post.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/el-interrogatorio-en-derecho\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-21T12:00:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/el-interrogatorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"La credibilidad en el interrogatorio, un valor a construir en Derecho\",\"datePublished\":\"2019-03-21T12:00:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/\"},\"wordCount\":719,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/el-interrogatorio.jpg\",\"keywords\":[\"Derecho Penal\",\"Interrogatorio\",\"Testigos\"],\"articleSection\":[\"Ejercicio Profesional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/\",\"name\":\"La credibilidad en el interrogatorio, un valor a construir en Derecho\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/el-interrogatorio.jpg\",\"datePublished\":\"2019-03-21T12:00:14+00:00\",\"description\":\"El interrogatorio para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante en el ejercicio legal. De eso va este post.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/el-interrogatorio.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/el-interrogatorio.jpg\",\"width\":1024,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/el-interrogatorio-en-derecho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La credibilidad en el interrogatorio, un valor a construir en Derecho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La credibilidad en el interrogatorio, un valor a construir en Derecho","description":"El interrogatorio para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante en el ejercicio legal. De eso va este post.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/el-interrogatorio-en-derecho\/","og_locale":"es_ES","og_type":"article","og_title":"La credibilidad en el interrogatorio, un valor a construir en Derecho","og_description":"El interrogatorio para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante en el ejercicio legal. De eso va este post.","og_url":"https:\/\/venfort.com\/es\/el-interrogatorio-en-derecho\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2019-03-21T12:00:14+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/el-interrogatorio.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"La credibilidad en el interrogatorio, un valor a construir en Derecho","datePublished":"2019-03-21T12:00:14+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/"},"wordCount":719,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/el-interrogatorio.jpg","keywords":["Derecho Penal","Interrogatorio","Testigos"],"articleSection":["Ejercicio Profesional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/","url":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/","name":"La credibilidad en el interrogatorio, un valor a construir en Derecho","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/el-interrogatorio.jpg","datePublished":"2019-03-21T12:00:14+00:00","description":"El interrogatorio para los testigos que sustentan la teor\u00eda de defensa es un aspecto importante en el ejercicio legal. De eso va este post.","breadcrumb":{"@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/el-interrogatorio-en-derecho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/el-interrogatorio.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/el-interrogatorio.jpg","width":1024,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/el-interrogatorio-en-derecho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"La credibilidad en el interrogatorio, un valor a construir en Derecho"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2610"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2611"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}