{"id":2614,"date":"2019-03-07T08:00:01","date_gmt":"2019-03-07T12:00:01","guid":{"rendered":"https:\/\/venfort.com\/?p=888"},"modified":"2019-03-07T08:00:01","modified_gmt":"2019-03-07T12:00:01","slug":"corrupcion-latinoamerica-delitos","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/corrupcion-latinoamerica-delitos\/","title":{"rendered":"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La corrupci\u00f3n es definida como el abuso del poder encomendado para beneficio personal, seg\u00fan la organizaci\u00f3n no gubernamental Transparencia Internacional, encargada de medir la percepci\u00f3n de corrupci\u00f3n en el sector p\u00fablico en pa\u00edses determinados. Puede ser catalogada como un fen\u00f3meno socio &#8211; econ\u00f3mico nocivo, diverso y global que socava las bases de una sociedad y puede incluir una gran serie de actividades y de redes que operan en el seno de instituciones de gran relevancia para el funcionamiento de una naci\u00f3n. <br><\/p><\/blockquote>\n\n\n\n<p><strong>Entre la vasta gama de acciones que pueden ser identificadas como corruptas<\/strong> se encuentran LA CORRUPCI\u00d3N \u2014ENTRE PARTICULARES, PROPIA E IMPROPIA, CALIFICADA, INDUCCI\u00d3N\u2014, PECULADO, MALVERSACI\u00d3N, EVASI\u00d3N DE LICITACI\u00d3N, SOBREGIRO PRESUPUESTARIO, CONCUSI\u00d3N USO DE INFORMACI\u00d3N RESERVADA, ABUSO DE AUTORIDAD EXACCIONES ILEGALES, CONCIERTO CON CONTRATISTAS, TR\u00c1FICO DE INFLUENCIAS, LUCRO EN ACTOS ADMINISTRATIVOS, ENRIQUECIMIENTO IL\u00cdCITO, SUPOSICI\u00d3N DE VALIMIENTO, SOBORNO TRANSNACIONAL, OMISI\u00d3N DE PRONUNCIAMIENTO, RETARDO DOLOSO DEL PROCESO JURISDICCIONAL, entre otros tipos penales. <br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El inicio de la corrupci\u00f3n<\/h2>\n\n\n\n<p><strong>La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada<\/strong>. Puede comenzar con peque\u00f1os actos de ciudadanos como el pago de sobornos a polic\u00edas para evitar multas, o la utilizaci\u00f3n de gestores para facilitar la obtenci\u00f3n de documentaci\u00f3n oficial necesaria en diversos tr\u00e1mites civiles. A gran escala se manifiesta en la \u00abgran corrupci\u00f3n\u00bb, catalogada como el desv\u00edo de los fondos pertenecientes a un Estado para el uso ilegal y personal de un individuo o un grupo de individuos. Que resulta altamente costosa en t\u00e9rminos de dinero y de da\u00f1os infligidos <a href=\"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos-2\/\">a los derechos humanos<\/a>. Es en este tipo de corrupci\u00f3n, sobre todo, que Am\u00e9rica Latina tiene mucho que contar y trascender, seg\u00fan las estad\u00edsticas y an\u00e1lisis de expertos. <br><\/p>\n\n\n\n<p><strong>Las tierras latinoamericanas son altamente ricas en t\u00e9rminos de recursos naturales y extracci\u00f3n de materia prima<\/strong> para innumerables productos de utilidad para la humanidad. Sin &nbsp;embargo, las pr\u00e1cticas para manejar este patrimonio no se han ajustado a los requerimientos legales para evitar el flagelo de la corrupci\u00f3n. Pareciera que las leyes aplicadas no han sido lo suficientemente efectivas para prevenir este delito que termina impactando a todos los habitantes de un pa\u00eds, debido a que al desviar los fondos se les priva de mejoras en su calidad de vida que los gobiernos deber\u00edan garantizar en \u00e1reas como la salud, la educaci\u00f3n, la vivienda, el transporte, entre otras.<br><\/p>\n\n\n\n<p><strong>A pesar de que el costo real de este delito es dif\u00edcil de cuantificar<\/strong>, la organizaci\u00f3n Global Financial Integrity calcul\u00f3 que Am\u00e9rica Latina perdi\u00f3 el equivalente a 3% de su Producto Interno Bruto en manos de la corrupci\u00f3n entre 2003 y 2012. Este problema figuraba entre las cuatro circunstancias que m\u00e1s afectaba a la poblaci\u00f3n de 18 pa\u00edses de la regi\u00f3n, seg\u00fan la encuesta Latinobar\u00f3metro realizada en 2017 <br><\/p>\n\n\n\n<p><strong>Las estad\u00edsticas m\u00e1s recientes no son m\u00e1s alentadoras<\/strong>. El panorama parece indicar que a pesar de algunos esfuerzos la regi\u00f3n no logra avanzar en la batalla contra la corrupci\u00f3n. El \u00cdndice de Percepci\u00f3n de la Corrupci\u00f3n en la regi\u00f3n se ha mantenido en 44 sobre 100 durante tres a\u00f1os consecutivos. Este estudio es realizado por la organizaci\u00f3n no gubernamental Transparencia Internacional, y en \u00e9l se mide en una escala del 0 al 100 (representando el 100 la ausencia de corrupci\u00f3n) la percepci\u00f3n de corrupci\u00f3n en el sector p\u00fablico en un pa\u00eds determinado. <\/p>\n\n\n\n<p><strong>Las cifras obtenidas en Latinoam\u00e9rica son muy similares a las registradas en Asia Pac\u00edfico<\/strong>. Canad\u00e1 es el pa\u00eds con mayor puntuaci\u00f3n en el \u00edndice, seguido por Estados Unidos de Am\u00e9rica y Uruguay. Por su parte, Venezuela registr\u00f3 una de las puntuaciones m\u00e1s bajas de la regi\u00f3n al obtener 18 puntos, mientras que Hait\u00ed alcanz\u00f3 20 puntos y Nicaragua 25. Esta cifra, seg\u00fan la organizaci\u00f3n \u00abrefleja la corrupci\u00f3n sistem\u00e1tica y persistente en Venezuela\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Para Transparencia Internacional las razones por las que se presentan estos \u00edndices tan bajos est\u00e1n relacionadas con el auge de liderazgos populistas que tienen a tomar las siguientes medidas:<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Bloqueo los medios de comunicaci\u00f3n libres e independientes.<\/li><li>Control y silenciamiento a la sociedad civil y a las organizaciones no gubernamentales.<\/li><li>Debilitamiento del sistema judicial y aumento del poder Ejecutivo.<\/li><li>Socavamiento de las garant\u00edas democr\u00e1ticas.<\/li><\/ul>\n\n\n\n<p><strong>Algunos pa\u00edses de la regi\u00f3n han demostrado un importante crecimiento en esta materia<\/strong>. Tal es el caso de Ecuador y El Salvador con 34 y 35 puntos respectivamente y que han incrementado en 2 puntos su r\u00e9cord anterior. De igual manera, Argentina ha registrado una alza consecutiva en los \u00faltimos 4 a\u00f1os. Un denominador com\u00fan en estas naciones ha sido el inter\u00e9s de sus gobiernos de promover investigaciones y el enjuiciamiento de casos de corrupci\u00f3n cometidos por funcionarios de alto nivel.<br><\/p>\n\n\n\n<p><strong>Uno de los casos de corrupci\u00f3n recientes m\u00e1s sonado y de mayor envergadura<\/strong>, en cuanto a la gran cantidad de pa\u00edses de la regi\u00f3n que involucr\u00f3, fue el esc\u00e1ndalo protagonizado por la constructora brasile\u00f1a Odebrecht, por el cual tambi\u00e9n fue enjuiciado el ex presidente de Brasil, Lula Da Silva. El caso Odebrecht figura como el mayor de los sobornos extranjeros en la historia, seg\u00fan el Departamento de Justicia de Estados Unidos, debido a que la compa\u00f1\u00eda lleg\u00f3 a pagar cientos de millones de d\u00f3lares en sobornos para adjudicarse grandes obras de infraestructura en diversos pa\u00edses.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Transparencia Internacional recomiendo las siguientes medidas para detener y prevenir la corrupci\u00f3n en Latinoam\u00e9rica:<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Defender el sistema democr\u00e1tico y las leyes anticorrupci\u00f3n.<\/li><li>Fortalecer a las instituciones encargadas del control y equilibrio del poder estatal.<\/li><li>Fortalecer a las instituciones judiciales y de seguimiento para vigilar la entrada y el fin \u00faltimo de los recursos p\u00fablicos.<\/li><li>Evitar el deterioro del derecho a la informaci\u00f3n y de la prensa independiente, pues son herramientas para evidenciar actos de corrupci\u00f3n.<\/li><\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Adicionalmente en Alan Aldana &amp; Abogados consideramos la necesaria inclusi\u00f3n como cr\u00edmenes de lesa humanidad a los grandes delitos econ\u00f3micos y financieros, los cuales deben ser tipificados <a href=\"https:\/\/venfort.com\/the-code-jurisdiccion-universal\/\">en un nuevo c\u00f3digo de Justicia Universal<\/a>, en el cual se incluyan procedimientos \u00e1giles para la incautaci\u00f3n, confiscaci\u00f3n y repatriaci\u00f3n de los bienes recuperados.<br><\/p><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Fuentes consultadas:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\"El Tiempo (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.eltiempo.com\/mundo\/latinoamerica\/lucha-anticorrupcion-en-latinoamerica-tiene-muchas-normas-y-poca-transparencia-226074\" target=\"_blank\">El Tiempo<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"BBC (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.bbc.com\/mundo\/noticias-internacional-43930080\" target=\"_blank\">BBC<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"blogs.iadb.org (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/blogs.iadb.org\/administracion-publica\/es\/siguiendo-la-pista-al-dinero-del-delito-en-america-latina\/\" target=\"_blank\">blogs.iadb.org<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"oecd.org (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.oecd.org\/daf\/anti-bribery\/programa-anticorrupcion-ocde-para-america-latina.htm\" target=\"_blank\">oecd.org<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"transparency.org (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.transparency.org\/news\/feature\/el_debilitamiento_de_la_democracia_y_el_auge_del_populismo_en_las_americas\" target=\"_blank\">transparency.org<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"El Nacional (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/www.el-nacional.com\/noticias\/mundo\/lucha-anticorrupcion-latinoamericana-muchas-normas-poca-transparencia_233856\" target=\"_blank\">El Nacional<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"Gfintegrity.org (abre en una nueva pesta\u00f1a)\" href=\"https:\/\/www.gfintegrity.org\/\" target=\"_blank\">Gfintegrity.org<\/a><\/li><li><a href=\"http:\/\/thecodedoc.com\/es\/inicio\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"The Code (abre en una nueva pesta\u00f1a)\">The Code<\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La corrupci\u00f3n es definida como el abuso del poder encomendado para beneficio personal, seg\u00fan la organizaci\u00f3n no gubernamental Transparencia Internacional, encargada de medir la percepci\u00f3n de corrupci\u00f3n en el sector p\u00fablico en pa\u00edses determinados. Puede ser catalogada como un fen\u00f3meno socio &#8211; econ\u00f3mico nocivo, diverso y global que socava las bases de una sociedad y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2615,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[25],"tags":[237,265],"class_list":["post-2614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jurisdiccion-internacional","tag-delito-de-corrupcion","tag-latinoamerica","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica<\/title>\n<meta name=\"description\" content=\"La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada. En este art\u00edculo abordamos este flagelo en la regi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/corrupcion-latinoamerica-delitos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica\" \/>\n<meta property=\"og:description\" content=\"La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada. En este art\u00edculo abordamos este flagelo en la regi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/corrupcion-latinoamerica-delitos\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-07T12:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/corrupcion-latinoamerica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica\",\"datePublished\":\"2019-03-07T12:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/\"},\"wordCount\":1113,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/corrupcion-latinoamerica.jpg\",\"keywords\":[\"delito de corrupci\u00f3n\",\"latinoamerica\"],\"articleSection\":[\"Jurisdicci\u00f3n Internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/\",\"name\":\"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/corrupcion-latinoamerica.jpg\",\"datePublished\":\"2019-03-07T12:00:01+00:00\",\"description\":\"La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada. En este art\u00edculo abordamos este flagelo en la regi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/corrupcion-latinoamerica.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/corrupcion-latinoamerica.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/corrupcion-latinoamerica-delitos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica","description":"La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada. En este art\u00edculo abordamos este flagelo en la regi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/corrupcion-latinoamerica-delitos\/","og_locale":"es_ES","og_type":"article","og_title":"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica","og_description":"La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada. En este art\u00edculo abordamos este flagelo en la regi\u00f3n.","og_url":"https:\/\/venfort.com\/es\/corrupcion-latinoamerica-delitos\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2019-03-07T12:00:01+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/corrupcion-latinoamerica.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica","datePublished":"2019-03-07T12:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/"},"wordCount":1113,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/corrupcion-latinoamerica.jpg","keywords":["delito de corrupci\u00f3n","latinoamerica"],"articleSection":["Jurisdicci\u00f3n Internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/","url":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/","name":"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/corrupcion-latinoamerica.jpg","datePublished":"2019-03-07T12:00:01+00:00","description":"La corrupci\u00f3n no es un mal exclusivo de una naci\u00f3n o una regi\u00f3n determinada. En este art\u00edculo abordamos este flagelo en la regi\u00f3n.","breadcrumb":{"@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/corrupcion-latinoamerica.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2019\/03\/corrupcion-latinoamerica.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/corrupcion-latinoamerica-delitos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"La corrupci\u00f3n, un flagelo que ensombrece a Latinoam\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2614"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2614\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2615"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}