{"id":2736,"date":"2017-12-07T15:08:06","date_gmt":"2017-12-07T19:08:06","guid":{"rendered":"https:\/\/venfort.com\/?p=406"},"modified":"2017-12-07T15:08:06","modified_gmt":"2017-12-07T19:08:06","slug":"dia-internacional-de-los-derechos-humanos","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/dia-internacional-de-los-derechos-humanos\/","title":{"rendered":"Rumbo a los 70 a\u00f1os de aspirar por un mundo m\u00e1s justo"},"content":{"rendered":"<blockquote><p>Defender la equidad, la justicia y la dignidad humana han sido las luchas m\u00e1s importantes que ha enfrentado la humanidad durante la \u00e9poca contempor\u00e1nea. Despu\u00e9s de guerras mundiales, conflictos b\u00e9licos y delitos graves a los principios b\u00e1sicos universales, se tom\u00f3 la consciencia de formalizar una serie de condiciones para garantizar la integridad y el respeto a la vida.<\/p><\/blockquote>\n<h2>D\u00eda Internacional de los Derechos Humanos<\/h2>\n<p><strong>En acuerdo, el 10 de diciembre de 1948 la Asamblea General de la Organizaci\u00f3n de las Naciones Unidas<\/strong> (ONU) adopt\u00f3 la Declaraci\u00f3n Universal de los Derechos Humanos proclamando estas garant\u00edas inalienables e inherentes a todos los seres humanos, independientemente de su raza, religi\u00f3n, sexo, idioma, cultura u opiniones pol\u00edticas.<\/p>\n<p>La Declaraci\u00f3n, redactada por representantes de distintos contextos jur\u00eddicos, sociales y culturales del mundo, dicta los valores universales y una idea com\u00fan a seguir por todos los pueblos y naciones.<\/p>\n<p>A pesar de que es una declaraci\u00f3n viva y susceptible a modificaciones, la universalidad de sus principios y la eficacia que ha demostrado para resolver casos de violaciones a los derechos humanos la convierte en un texto sin vencimiento.<\/p>\n<p><strong>El documento, con 500 versiones en idiomas, establece que todos los seres humanos tienen el mismo valor<\/strong> y as\u00ed debe ser considerado ante todas las instancias civiles, gubernamentales y jur\u00eddicas. La proclamaci\u00f3n m\u00e1s traducida en el planeta ha sentado las bases para fortalecer la dignidad de los ciudadanos y hacer del mundo un lugar m\u00e1s justo.<\/p>\n<p><strong>Estando a pocos pasos de cumplir 70 a\u00f1os de la creaci\u00f3n de la Declaraci\u00f3n<\/strong>, la ONU insta a continuar en la lucha por la defensa de estos valores que fortalecen a toda la humanidad y abarcan todos los aspectos de la vida como ciudadano, sin importar el lugar o las condiciones circunstanciales. Se trata de una verdad insondable y que fija los lineamientos sobre los cuales los Estados deben regirse para legislar en esta materia, as\u00ed como tambi\u00e9n aportan informaci\u00f3n importante para que los ciudadanos puedan defenderse ante cualquier atropello de este tipo.<\/p>\n<h2>Dignidad a preservar<\/h2>\n<p><strong>Los derechos humanos son interrelacionados, interdependientes e indivisibles.<\/strong> Est\u00e1n contemplados en la ley y garantizados por ella, a trav\u00e9s de figuras legales como tratados, el derecho internacional consuetudinario, los principios generales y otras fuentes del derecho internacional.<\/p>\n<p><strong>Con estas regulaciones se establecen las medidas que tienen que tomar los gobiernos<\/strong> frente a determinadas situaciones, a fin de promover y proteger los principios y las libertades fundamentales de los individuos o grupos.<\/p>\n<p><strong>El principio de universalidad es de las cualidades m\u00e1s importantes de esta proclamaci\u00f3n<\/strong> pues dispone que todos los Estados tienen el deber \u2014independientemente de sus sistemas pol\u00edticos, econ\u00f3micos y culturales\u2014 de promover y velar por la salvaguarda de estas garant\u00edas. En ese sentido todos los Estados han ratificado al menos uno de estos instrumentos legales y 80% de ellos lo han hecho con cuatro o m\u00e1s de los principales tratados de derechos humanos, seg\u00fan datos de la ONU.<\/p>\n<h2>Sobre la No discriminaci\u00f3n<\/h2>\n<p><strong>De igual manera, la no discriminaci\u00f3n es un principio transversal<\/strong> en el derecho internacional de los derechos humanos. Esta garant\u00eda se aplica a toda persona en relaci\u00f3n con todos los derechos humanos y las libertades, y proh\u00edbe la discriminaci\u00f3n en categor\u00edas tales como sexo, raza, color, entre otras. Se complementa con el principio de igualdad contemplado en la Declaraci\u00f3n Universal y que reza: \u00abTodos los seres humanos nacen libres e iguales en dignidad y derechos\u00bb.<\/p>\n<p><strong>La protecci\u00f3n de estos derechos tambi\u00e9n est\u00e1 en manos de organismos internacionales<\/strong> tales como el <a href=\"https:\/\/venfort.com\/sistema-interamericano-derechos-humanos\/#.WibEFtLibIU\">Sistema Interamericano<\/a> de Derechos Humanos, cuya misi\u00f3n es promover la protecci\u00f3n regional de las garant\u00edas bajo cualquier circunstancia y actuar legalmente, cuando sea necesario, a trav\u00e9s de la Corte Interamericana de Derechos Humanos.<\/p>\n<p><strong>En Alan Aldana &amp; Abogados fomentamos la protecci\u00f3n de estos principios universales e indivisibles<\/strong> a trav\u00e9s de los mecanismos que ofrece la Justicia Internacional, conscientes de que su aplicaci\u00f3n es una forma de prevenir los cr\u00edmenes de lesa humanidad.<\/p>\n<p><strong>Fuentes consultadas:<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/www.un.org\/es\/events\/humanrightsday\/\" target=\"_blank\" rel=\"noopener\">D\u00edas Internacionales ONU<\/a><\/li>\n<li><a href=\"http:\/\/www.ohchr.org\/SP\/Issues\/Pages\/WhatareHumanRights.aspx\" target=\"_blank\" rel=\"noopener\">Oficina del Alto Comisionado &#8211; ONU<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Defender la equidad, la justicia y la dignidad humana han sido las luchas m\u00e1s importantes que ha enfrentado la humanidad durante la \u00e9poca contempor\u00e1nea. Despu\u00e9s de guerras mundiales, conflictos b\u00e9licos y delitos graves a los principios b\u00e1sicos universales, se tom\u00f3 la consciencia de formalizar una serie de condiciones para garantizar la integridad y el respeto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2737,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[25],"tags":[53,95,455,111],"class_list":["post-2736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jurisdiccion-internacional","tag-abogados","tag-derechos-humanos","tag-dia-internacional","tag-onu","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Internacional de los Derechos Humanos: rumbo a los 70 a\u00f1os<\/title>\n<meta name=\"description\" content=\"El 10 de diciembre es el d\u00eda internacional de los Derechos Humanos, con este art\u00edculo queremos contribuir a la importancia de su divulgaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/dia-internacional-de-los-derechos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Internacional de los Derechos Humanos: rumbo a los 70 a\u00f1os\" \/>\n<meta property=\"og:description\" content=\"El 10 de diciembre es el d\u00eda internacional de los Derechos Humanos, con este art\u00edculo queremos contribuir a la importancia de su divulgaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/dia-internacional-de-los-derechos-humanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-07T19:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2017\/12\/dia-internacional-derechos-humanos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"Rumbo a los 70 a\u00f1os de aspirar por un mundo m\u00e1s justo\",\"datePublished\":\"2017-12-07T19:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/\"},\"wordCount\":720,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/dia-internacional-derechos-humanos.jpg\",\"keywords\":[\"Abogados\",\"Derechos Humanos\",\"D\u00eda Internacional\",\"ONU\"],\"articleSection\":[\"Jurisdicci\u00f3n Internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/\",\"name\":\"D\u00eda Internacional de los Derechos Humanos: rumbo a los 70 a\u00f1os\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/dia-internacional-derechos-humanos.jpg\",\"datePublished\":\"2017-12-07T19:08:06+00:00\",\"description\":\"El 10 de diciembre es el d\u00eda internacional de los Derechos Humanos, con este art\u00edculo queremos contribuir a la importancia de su divulgaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/dia-internacional-derechos-humanos.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/dia-internacional-derechos-humanos.jpg\",\"width\":1024,\"height\":684,\"caption\":\"Photo by Alice Donovan Rouse on Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/dia-internacional-de-los-derechos-humanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rumbo a los 70 a\u00f1os de aspirar por un mundo m\u00e1s justo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional de los Derechos Humanos: rumbo a los 70 a\u00f1os","description":"El 10 de diciembre es el d\u00eda internacional de los Derechos Humanos, con este art\u00edculo queremos contribuir a la importancia de su divulgaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/dia-internacional-de-los-derechos-humanos\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Internacional de los Derechos Humanos: rumbo a los 70 a\u00f1os","og_description":"El 10 de diciembre es el d\u00eda internacional de los Derechos Humanos, con este art\u00edculo queremos contribuir a la importancia de su divulgaci\u00f3n.","og_url":"https:\/\/venfort.com\/es\/dia-internacional-de-los-derechos-humanos\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2017-12-07T19:08:06+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/12\/dia-internacional-derechos-humanos.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"Rumbo a los 70 a\u00f1os de aspirar por un mundo m\u00e1s justo","datePublished":"2017-12-07T19:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/"},"wordCount":720,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/12\/dia-internacional-derechos-humanos.jpg","keywords":["Abogados","Derechos Humanos","D\u00eda Internacional","ONU"],"articleSection":["Jurisdicci\u00f3n Internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/","url":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/","name":"D\u00eda Internacional de los Derechos Humanos: rumbo a los 70 a\u00f1os","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/12\/dia-internacional-derechos-humanos.jpg","datePublished":"2017-12-07T19:08:06+00:00","description":"El 10 de diciembre es el d\u00eda internacional de los Derechos Humanos, con este art\u00edculo queremos contribuir a la importancia de su divulgaci\u00f3n.","breadcrumb":{"@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/12\/dia-internacional-derechos-humanos.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/12\/dia-internacional-derechos-humanos.jpg","width":1024,"height":684,"caption":"Photo by Alice Donovan Rouse on Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/dia-internacional-de-los-derechos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"Rumbo a los 70 a\u00f1os de aspirar por un mundo m\u00e1s justo"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2736"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2737"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}