{"id":2746,"date":"2017-11-02T08:00:22","date_gmt":"2017-11-02T12:00:22","guid":{"rendered":"https:\/\/venfort.com\/?p=367"},"modified":"2017-11-02T08:00:22","modified_gmt":"2017-11-02T12:00:22","slug":"estatuto-de-roma-jurisdiccion-internacional","status":"publish","type":"post","link":"https:\/\/venfort.com\/es\/estatuto-de-roma-jurisdiccion-internacional\/","title":{"rendered":"Estatuto de Roma: \u00bfCu\u00e1l es el campo de acci\u00f3n de la jurisdicci\u00f3n internacional en Venezuela?"},"content":{"rendered":"<p>La figura de la jurisdicci\u00f3n internacional se define como \u00ab<em>un principio jur\u00eddico que permite o exige a un Estado enjuiciar penalmente ciertos cr\u00edmenes, independientemente del lugar donde se hayan cometido y de la nacionalidad del autor y de la v\u00edctima<\/em>\u00bb, tal como se explica en la publicaci\u00f3n:<a href=\"https:\/\/venfort.com\/justicia-internacional-crimenes-humanidad\/\"> Los principios de jurisdicci\u00f3n universal<\/a> y complementariedad de la revista internacional Review of the Red Cross.<\/p>\n<p>Este principio del Derecho fue establecido en los cuatro convenios de Ginebra de 1949 y fue acu\u00f1ado por la necesidad de determinar responsabilidades legales ante los sucesos y violaciones a los derechos humanos ocurridas durante la II Guerra Mundial.<\/p>\n<p><strong>La pertinencia y utilidad de la figura jur\u00eddica fue tan evidente que en 1998 se instaur\u00f3 la<\/strong> <a href=\"https:\/\/www.icc-cpi.int\/\" target=\"_blank\" rel=\"noopener\">Corte Penal Internacional<\/a> como una entidad jur\u00eddica independiente que puede actuar frente a cr\u00edmenes de lesa humanidad, cr\u00edmenes de guerra, genocidio y agresi\u00f3n. Esta instituci\u00f3n est\u00e1 soportada en el Estatuto de Roma, cuya implementaci\u00f3n ha generado cambios importantes en el \u00e1rea de la justicia internacional.<\/p>\n<p><strong>Las leyes de cada Estado con respecto a la penalidad frente a este tipo de delito<\/strong> influyen de cierta forma en la aplicaci\u00f3n o acci\u00f3n de la legislaci\u00f3n establecida en el Estatuto de Roma. Venezuela fue uno de los primeros pa\u00edses en suscribir y ratificar el mencionado instrumento legal, a pesar de que su jurisdicci\u00f3n interna no contempla la posibilidad de la persecuci\u00f3n de delitos como el genocidio o lesa humanidad.<\/p>\n<h2>El Estatuto de Roma en Venezuela y la jurisdicci\u00f3n internacional<\/h2>\n<p><strong>Hasta el momento en territorio nacional el genocidio o el delito de lesa humanidad no es punible<\/strong>, salvo en el caso de las conductas punibles residuales que coincidan con la regulaci\u00f3n internacional.<\/p>\n<p><strong>Aunque suene parad\u00f3jico, de suceder en Venezuela conductas de este orden es indudable la manifestaci\u00f3n de la justicia internacional<\/strong>, pues el pa\u00eds suscribi\u00f3 el Estatuto de Roma sin que prevaleciese ning\u00fan tipo de cuestionamiento sobre los aspectos de sus normativas internas que contradijeran los lineamientos de la jurisdicci\u00f3n internacional.<\/p>\n<p>Sin embargo, es necesario que los pa\u00edses ajusten sus instrumentos legales a estos lineamientos internacionales tan apremiantes, a fin de no contradecir en ninguna de sus letras ni entorpecer la labor de estas instancias superiores.<\/p>\n<p><strong>Al suscribir y ratificar el Estatuto de Roma, Venezuela debe legislar a los fines de garantizar la tutela judicial efectiva en la competencia internacional<\/strong> a la que se comprometi\u00f3. Esto implica no limitarse a la aplicaci\u00f3n adjetiva gen\u00e9rica ofrecida por el C\u00f3digo Org\u00e1nico Procesal Venezolana y la Ley contra la Delincuencia Organizada y Financiamiento al Terrorismo, sino desarrollar tambi\u00e9n sistemas expedidos de la aplicaci\u00f3n internacional.<\/p>\n<blockquote>\n<p style=\"text-align: center;\">Desde Alan Aldana &amp; Abogados estudiamos todos los mecanismos legales con que cuenta Venezuela para hacer valer la justicia y condenar todos los delitos que atenten en contra de los derechos humanos.<br \/>\n<a href=\"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/EL-ESTATUTO-DE-ROMA-Y-SU-APLICACION-EN-VENEZUELA.pdf\" target=\"_blank\" rel=\"noopener\">Descarga el documento completo aqu\u00ed<\/a>.<\/p>\n<\/blockquote>\n<p><a href=\"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/EL-ESTATUTO-DE-ROMA-Y-SU-APLICACION-EN-VENEZUELA.pdf\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-370 size-full\" src=\"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/documento-estatuto-de-roma-aplicacion-venezuela.png\" alt=\"\" width=\"565\" height=\"778\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La figura de la jurisdicci\u00f3n internacional se define como \u00abun principio jur\u00eddico que permite o exige a un Estado enjuiciar penalmente ciertos cr\u00edmenes, independientemente del lugar donde se hayan cometido y de la nacionalidad del autor y de la v\u00edctima\u00bb, tal como se explica en la publicaci\u00f3n: Los principios de jurisdicci\u00f3n universal y complementariedad de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2748,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[25],"tags":[95,459,339,131,41],"class_list":["post-2746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jurisdiccion-internacional","tag-derechos-humanos","tag-estatuto-de-roma","tag-genocidio","tag-lesa-humanidad","tag-venezuela","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estatuto de Roma: \u00bfPuede actuar la justicia internacional en Venezuela?<\/title>\n<meta name=\"description\" content=\"Con este art\u00edculo queremos introducir el documento que realizamos llamado: El Estatuto de Roma y su aplicaci\u00f3n en Venezuela. \u00a1Desc\u00e1rgalo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/es\/estatuto-de-roma-jurisdiccion-internacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estatuto de Roma: \u00bfPuede actuar la justicia internacional en Venezuela?\" \/>\n<meta property=\"og:description\" content=\"Con este art\u00edculo queremos introducir el documento que realizamos llamado: El Estatuto de Roma y su aplicaci\u00f3n en Venezuela. \u00a1Desc\u00e1rgalo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/es\/estatuto-de-roma-jurisdiccion-internacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-02T12:00:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/estatuto-de-roma-venezuela-alan-aldana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"Estatuto de Roma: \u00bfCu\u00e1l es el campo de acci\u00f3n de la jurisdicci\u00f3n internacional en Venezuela?\",\"datePublished\":\"2017-11-02T12:00:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/estatuto-de-roma-venezuela-alan-aldana.jpg\",\"keywords\":[\"Derechos Humanos\",\"Estatuto de Roma\",\"Genocidio\",\"Lesa Humanidad\",\"Venezuela\"],\"articleSection\":[\"Jurisdicci\u00f3n Internacional\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/\",\"name\":\"Estatuto de Roma: \u00bfPuede actuar la justicia internacional en Venezuela?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/estatuto-de-roma-venezuela-alan-aldana.jpg\",\"datePublished\":\"2017-11-02T12:00:22+00:00\",\"description\":\"Con este art\u00edculo queremos introducir el documento que realizamos llamado: El Estatuto de Roma y su aplicaci\u00f3n en Venezuela. \u00a1Desc\u00e1rgalo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/estatuto-de-roma-venezuela-alan-aldana.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/estatuto-de-roma-venezuela-alan-aldana.jpg\",\"width\":1241,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/estatuto-de-roma-jurisdiccion-internacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estatuto de Roma: \u00bfCu\u00e1l es el campo de acci\u00f3n de la jurisdicci\u00f3n internacional en Venezuela?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/es\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estatuto de Roma: \u00bfPuede actuar la justicia internacional en Venezuela?","description":"Con este art\u00edculo queremos introducir el documento que realizamos llamado: El Estatuto de Roma y su aplicaci\u00f3n en Venezuela. \u00a1Desc\u00e1rgalo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/es\/estatuto-de-roma-jurisdiccion-internacional\/","og_locale":"es_ES","og_type":"article","og_title":"Estatuto de Roma: \u00bfPuede actuar la justicia internacional en Venezuela?","og_description":"Con este art\u00edculo queremos introducir el documento que realizamos llamado: El Estatuto de Roma y su aplicaci\u00f3n en Venezuela. \u00a1Desc\u00e1rgalo!","og_url":"https:\/\/venfort.com\/es\/estatuto-de-roma-jurisdiccion-internacional\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2017-11-02T12:00:22+00:00","og_image":[{"width":1241,"height":680,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/estatuto-de-roma-venezuela-alan-aldana.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"Escrito por":"VENFORT","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"Estatuto de Roma: \u00bfCu\u00e1l es el campo de acci\u00f3n de la jurisdicci\u00f3n internacional en Venezuela?","datePublished":"2017-11-02T12:00:22+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/"},"wordCount":513,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/estatuto-de-roma-venezuela-alan-aldana.jpg","keywords":["Derechos Humanos","Estatuto de Roma","Genocidio","Lesa Humanidad","Venezuela"],"articleSection":["Jurisdicci\u00f3n Internacional"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/","url":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/","name":"Estatuto de Roma: \u00bfPuede actuar la justicia internacional en Venezuela?","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/estatuto-de-roma-venezuela-alan-aldana.jpg","datePublished":"2017-11-02T12:00:22+00:00","description":"Con este art\u00edculo queremos introducir el documento que realizamos llamado: El Estatuto de Roma y su aplicaci\u00f3n en Venezuela. \u00a1Desc\u00e1rgalo!","breadcrumb":{"@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/estatuto-de-roma-venezuela-alan-aldana.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2017\/11\/estatuto-de-roma-venezuela-alan-aldana.jpg","width":1241,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/estatuto-de-roma-jurisdiccion-internacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"Estatuto de Roma: \u00bfCu\u00e1l es el campo de acci\u00f3n de la jurisdicci\u00f3n internacional en Venezuela?"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Venfort Abogados","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/es\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/comments?post=2746"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/posts\/2746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media\/2748"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/media?parent=2746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/categories?post=2746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/es\/wp-json\/wp\/v2\/tags?post=2746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}