{"id":2466,"date":"2020-07-23T16:40:00","date_gmt":"2020-07-23T20:40:00","guid":{"rendered":"https:\/\/venfort.com\/blog\/?p=1220"},"modified":"2020-07-23T16:40:00","modified_gmt":"2020-07-23T20:40:00","slug":"la-cour-penale-internationale-gardien-de-la-justice-dans-le-monde","status":"publish","type":"post","link":"https:\/\/venfort.com\/fr\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/","title":{"rendered":"La Cour p\u00e9nale internationale : un gardien de la justice dans le monde"},"content":{"rendered":"<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>L'action de la Cour p\u00e9nale internationale est r\u00e9gie par<\/strong><a href=\"https:\/\/venfort.com\/fr\/blog\/statut-de-rome-competence-internationale\/\"> le statut de Rome<\/a> qui est entr\u00e9 en vigueur le 2 juillet 2002. Elle est compos\u00e9e d'une pr\u00e9sidence, de sections judiciaires, d'un bureau du procureur et d'un greffe. L'Assembl\u00e9e des \u00c9tats parties n'est pas int\u00e9gr\u00e9e \u00e0 l'organigramme de la Cour afin de garantir son autonomie, mais cet organe l\u00e9gislatif est charg\u00e9 de superviser la mise en \u0153uvre des travaux de la Cour.<\/p><\/blockquote>\n\n\n\n<p><strong>En raison de la gravit\u00e9 des faits qui peuvent \u00eatre signal\u00e9s \u00e0 sa juridiction<\/strong> les crimes de premier et de second degr\u00e9, sa difficult\u00e9 \u00e0 enqu\u00eater sur ces crimes<strong>, <\/strong>\u00c9tant donn\u00e9 qu'un grand nombre de personnes, d'institutions et m\u00eame d'\u00c9tats sont g\u00e9n\u00e9ralement impliqu\u00e9s, un effort consid\u00e9rable d'ind\u00e9pendance dans l'enqu\u00eate et des talents particuliers pour trouver les donn\u00e9es n\u00e9cessaires sont n\u00e9cessaires pour d\u00e9terminer les responsabilit\u00e9s dans ces cas.<\/p>\n\n\n\n<p><strong>Compte tenu de la<\/strong><a href=\"https:\/\/venfort.com\/fr\/blog\/crime-contre-lhumanite\/\"><strong> crimes contre l'humanit\u00e9<\/strong><\/a><strong>, g\u00e9nocides, crimes d'agression, g\u00e9nocides, crimes d'agression<\/strong> et les crimes de guerre qui ont \u00e9t\u00e9 commis dans le monde entier \u00e0 diff\u00e9rentes \u00e9poques et qui n'ont pas toujours \u00e9t\u00e9 d\u00fbment punis, la Cour p\u00e9nale internationale a vu le jour pour tenter de rendre justice dans ces affaires, qui ont eu un fort impact sur le monde.<\/p>\n\n\n\n<p><strong>Il a commenc\u00e9 \u00e0 fonctionner en 2003 en tant que tribunal permanent. <\/strong>de dernier recours pour la poursuite des crimes graves et a remplac\u00e9 les tribunaux ad hoc \u00e9tablis au cours de l'histoire de l'Union europ\u00e9enne.<a href=\"http:\/\/www.dicc.hegoa.ehu.es\/listar\/mostrar\/152\"> nations unies<\/a>, Le Tribunal pour l'ex-Yougoslavie (1993) et le Tribunal pour le Rwanda (1994). Deux pr\u00e9c\u00e9dents existaient auparavant : les tribunaux militaires de Nuremberg et de Tokyo, cr\u00e9\u00e9s par les pays victorieux de la Seconde Guerre mondiale pour juger les vaincus. En revanche, les tribunaux pour l'ex-Yougoslavie et le Rwanda ont \u00e9t\u00e9 cr\u00e9\u00e9s par le Conseil de s\u00e9curit\u00e9, qui a interpr\u00e9t\u00e9 la commission de massacres et d'autres violations graves des droits de l'homme dans ces pays comme une violation du droit international.<a href=\"http:\/\/www.dicc.hegoa.ehu.es\/listar\/mostrar\/59\"> le droit international humanitaire<\/a> constituait une menace pour la paix et la s\u00e9curit\u00e9 internationales.&nbsp;<\/p>\n\n\n\n<p><strong>C'est pourquoi il faut remonter aux origines et se souvenir des illustres<\/strong> <strong><a href=\"https:\/\/venfort.com\/fr\/blog\/holocauste-genocide\/\">Raphael Lemkin<\/a><\/strong> qui, en plus de cr\u00e9er le mot <strong>G\u00e9nocide<\/strong>, Il a \u00e9galement \u00e9t\u00e9 victime et a pu r\u00e9aliser le but de sa vie en \u00e9tant la force motrice de la convention pour la pr\u00e9vention et la r\u00e9pression de ce crime, qui devrait avoir pour d\u00e9nominateur commun d'\u00eatre <strong>perp\u00e9tr\u00e9 dans l'intention de d\u00e9truire en tout ou en partie un groupe national, ethnique, racial ou religieux en tant que tel, et certains doctrinaires modernes ont inclus la th\u00e8se du g\u00e9nocide politique.<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ces caract\u00e9ristiques de l'infraction ont \u00e9t\u00e9 reprises dans l'article 6 du Statut de Rome qui \u00e9rige ces actions en infractions p\u00e9nales :<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Mise \u00e0 mort de membres du groupe ;<\/li><li>Atteinte grave \u00e0 l'int\u00e9grit\u00e9 physique ou mentale des membres du groupe ;<\/li><li>Soumission intentionnelle du groupe \u00e0 des conditions d'existence qui aboutiront \u00e0 sa destruction physique, en tout ou en partie ;<\/li><li>Mesures de pr\u00e9vention des naissances au sein du groupe ;<\/li><li>Le transfert forc\u00e9 d'enfants du groupe vers un autre groupe.&nbsp;<\/li><\/ul>\n\n\n\n<p>De m\u00eame, l'article 7 du statut indique que les crimes contre l'humanit\u00e9 doivent avoir pour objet <strong>une attaque g\u00e9n\u00e9ralis\u00e9e ou syst\u00e9matique contre une population civile et en ayant connaissance de cette attaque en relation avec les crimes d'agression et d'intimidation.<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>&nbsp;Meurtre ;<\/li><li>Extermination ;<\/li><li>L'esclavage ;&nbsp;<\/li><li>D\u00e9portation ou transfert forc\u00e9 de population ; emprisonnement ou autre privation grave de libert\u00e9 physique en violation des r\u00e8gles fondamentales du droit international ;<\/li><li><a href=\"https:\/\/venfort.com\/fr\/blog\/la-torture-nuit-a-lintegrite\/\">Torture<\/a>;<\/li><li>Le viol, l'esclavage sexuel, la prostitution forc\u00e9e, la grossesse forc\u00e9e, la st\u00e9rilisation forc\u00e9e ou d'autres abus sexuels de gravit\u00e9 comparable ;<\/li><li>Pers\u00e9cution d'un groupe ou d'une collectivit\u00e9 ayant une identit\u00e9 distincte pour des motifs politiques, raciaux, nationaux, ethniques, culturels, religieux, de genre ou autres, universellement reconnus comme inacceptables en vertu du droit international ;<\/li><li>Disparition forc\u00e9e de personnes ;<\/li><li>Le crime de l'apartheid ;<\/li><li>Autres actes inhumains de nature similaire causant intentionnellement de grandes souffrances ou des atteintes graves \u00e0 l'int\u00e9grit\u00e9 physique ou \u00e0 la sant\u00e9 mentale ou physique.&nbsp;<\/li><\/ul>\n\n\n\n<p>Ne pas oublier dans le statut <strong>Crimes de guerre <\/strong>dans son article 8.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Comment d\u00e9bute une enqu\u00eate de la CPI ?<\/h2>\n\n\n\n<p><a href=\"https:\/\/venfort.com\/fr\/blog\/enquete-preliminaire-cour-penale-internationale\/#.Xws7uihKgdU\">D\u00e9but de l'enqu\u00eate de la CPI<\/a> lorsque les crimes ont \u00e9t\u00e9 commis par un \u00c9tat partie national, sur le territoire d'un \u00c9tat partie ou dans un \u00c9tat qui a accept\u00e9 la comp\u00e9tence de la Cour. Les crimes d\u00e9f\u00e9r\u00e9s au procureur de la CPI par le Conseil de s\u00e9curit\u00e9 des Nations unies sont \u00e9galement pris en compte.<\/p>\n\n\n\n<p><strong>Par l'interm\u00e9diaire de son bureau du procureur, la Cour examine s'il existe des preuves suffisantes de crimes graves relevant de la comp\u00e9tence du tribunal international.<\/strong> En outre, elle \u00e9value l'existence de v\u00e9ritables proc\u00e9dures nationales, ainsi que la possibilit\u00e9 que l'ouverture d'une enqu\u00eate approfondie serve les int\u00e9r\u00eats de la justice et des victimes concern\u00e9es. Si la situation correspond aux lignes directrices exig\u00e9es par la Cour, les suspects \u00e9ventuels sont identifi\u00e9s et une enqu\u00eate plus approfondie est ouverte.<\/p>\n\n\n\n<p><strong>Une fois que les auditions pertinentes ont eu lieu, au stade de la preuve,<\/strong> Les juges \u00e9valuent tous les \u00e9l\u00e9ments de preuve et rendent un verdict pour condamner les suspects. Les peines prononc\u00e9es par la CPI peuvent aller jusqu'\u00e0 30 ans d'emprisonnement ou, dans des circonstances exceptionnelles, jusqu'\u00e0 la r\u00e9clusion \u00e0 perp\u00e9tuit\u00e9.<\/p>\n\n\n\n<p><strong>En 2006, la Cour p\u00e9nale internationale a prononc\u00e9 la premi\u00e8re condamnation de Thomas Lubanga.<\/strong>, En 2009, elle a inculp\u00e9 pour la premi\u00e8re fois un chef d'\u00c9tat (Soudan), Omar al-Bashir, pour crimes de guerre et crimes contre l'humanit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nouvelles de la Cour p\u00e9nale internationale<\/h2>\n\n\n\n<p><strong>Ce tribunal a proc\u00e9d\u00e9 \u00e0 l'ouverture d'une enqu\u00eate pr\u00e9liminaire pour le compte du gouvernement v\u00e9n\u00e9zu\u00e9lien.<\/strong>, L'enqu\u00eate a \u00e9t\u00e9 lanc\u00e9e en f\u00e9vrier 2018 par la procureure Fatou Bensouda afin d'\u00e9valuer s'il existe des motifs d'enqu\u00eater sur l'\u00c9tat v\u00e9n\u00e9zu\u00e9lien concernant les all\u00e9gations de recours excessif \u00e0 la force par les agences de s\u00e9curit\u00e9 de l'\u00c9tat lors des manifestations de 2017. L'enqu\u00eate a \u00e9t\u00e9 ouverte en f\u00e9vrier 2018 par la procureure Fatou Bensouda dans le but d'\u00e9valuer s'il existe des motifs d'enqu\u00eater sur l'\u00c9tat v\u00e9n\u00e9zu\u00e9lien concernant les all\u00e9gations re\u00e7ues au sujet de la situation de protestation.&nbsp;<\/p>\n\n\n\n<p>Dans le cas du Venezuela, il a \u00e9t\u00e9 controvers\u00e9 parce qu'il y a une grande confrontation internationale de nature politique, qui g\u00e9n\u00e8re un proc\u00e8s parall\u00e8le \u00e0 travers les m\u00e9dias qui diffusent les nouvelles des porte-parole politiques.<\/p>\n\n\n\n<p>On le trouve \u00e9galement dans <strong>enqu\u00eate pr\u00e9liminaire <\/strong>de pays tels que <strong>Nigeria, Colombie, Guin\u00e9e, Palestine et Ukraine <\/strong>pour des crimes de guerre et des crimes contre l'humanit\u00e9 pr\u00e9sum\u00e9s.<\/p>\n\n\n\n<p>Il s'agit d'une question pr\u00e9occupante et <strong>Les attaques contre la Cour p\u00e9nale internationale constituent une violation du principe de progressivit\u00e9 des droits de l'homme et doivent \u00eatre trait\u00e9es par la communaut\u00e9 internationale, <\/strong>y compris de la part de pays qui, malheureusement, n'ont pas encore souhait\u00e9 devenir membres ; un exemple r\u00e9cent est celui de l'actuel gouvernement am\u00e9ricain<strong> qui, en pleine pand\u00e9mie de grippe aviaire, a impos\u00e9, par l'interm\u00e9diaire de l'OFAC, des sanctions au d\u00e9partement du Tr\u00e9sor \u00e0 l'encontre des fonctionnaires de la Cour.<\/strong> qui ont enqu\u00eat\u00e9 sur l'implication des forces am\u00e9ricaines dans des crimes de guerre en Afghanistan. <strong>Ces sanctions comprennent le blocage des actifs des employ\u00e9s de la Cour et l'interdiction d'entrer sur le territoire am\u00e9ricain.<\/strong><\/p>\n\n\n\n<p><strong>Ces actions ont \u00e9t\u00e9 d\u00e9crites par la Cour p\u00e9nale internationale comme une tentative d'interf\u00e9rer avec la l\u00e9galit\u00e9.<\/strong> et l'\u00c9tat de droit.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">C'est pourquoi, chez Alan Aldana &amp; Abogados, en tant qu'experts en droit p\u00e9nal international, nous soutenons la Cour p\u00e9nale internationale et nous esp\u00e9rons que, dans son \u00e9volution et celle du principe de progressivit\u00e9 des droits de l'homme, elle pourra garantir la protection judiciaire effective de toutes les affaires dont elle est saisie, de sorte que<strong> <a href=\"https:\/\/venfort.com\/fr\/blog\/paradigme-de-la-competence-universelle\/\">nous proposons un nouveau code de comp\u00e9tence universelle<\/a> <\/strong>pr\u00e9venir et punir d'autres crimes qui affectent la civilisation et le d\u00e9veloppement de l'humanit\u00e9, tels que le crime contre l'humanit\u00e9. <strong>Ecocide<\/strong>.<\/h3>","protected":false},"excerpt":{"rendered":"<p>La actuaci\u00f3n de la Corte Penal Internacional est\u00e1 regida por el Estatuto de Roma que entr\u00f3 en rigor el 2 de julio de 2002. Est\u00e1 compuesta por una Presidencia, Divisiones Judiciales, Oficina del Fiscal y Secretar\u00eda. La Asamblea de los Estados Parte no est\u00e1 integrada en el organigrama de la corte para garantizar su autonom\u00eda, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2467,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[25],"tags":[167,79,131],"class_list":["post-2466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jurisdiccion-internacional","tag-corte-penal-internacional","tag-derecho-penal","tag-lesa-humanidad","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Corte Penal Internacional: un vigilante de la justicia en el mundo<\/title>\n<meta name=\"description\" content=\"La actuaci\u00f3n de la Corte Penal Internacional est\u00e1 regida por el Estatuto de Roma que entr\u00f3 en rigor el 2 de julio de 2002.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/fr\/la-cour-penale-internationale-gardien-de-la-justice-dans-le-monde\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Corte Penal Internacional: un vigilante de la justicia en el mundo\" \/>\n<meta property=\"og:description\" content=\"La actuaci\u00f3n de la Corte Penal Internacional est\u00e1 regida por el Estatuto de Roma que entr\u00f3 en rigor el 2 de julio de 2002.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/fr\/la-cour-penale-internationale-gardien-de-la-justice-dans-le-monde\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T20:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2020\/07\/corte-penal-internacional.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"La Corte Penal Internacional: un vigilante de la justicia en el mundo\",\"datePublished\":\"2020-07-23T20:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/\"},\"wordCount\":1398,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/corte-penal-internacional.jpg\",\"keywords\":[\"Corte Penal Internacional\",\"Derecho Penal\",\"Lesa Humanidad\"],\"articleSection\":[\"Jurisdicci\u00f3n Internacional\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/\",\"name\":\"La Corte Penal Internacional: un vigilante de la justicia en el mundo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/corte-penal-internacional.jpg\",\"datePublished\":\"2020-07-23T20:40:00+00:00\",\"description\":\"La actuaci\u00f3n de la Corte Penal Internacional est\u00e1 regida por el Estatuto de Roma que entr\u00f3 en rigor el 2 de julio de 2002.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/corte-penal-internacional.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/corte-penal-internacional.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Corte Penal Internacional: un vigilante de la justicia en el mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/fr\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Cour p\u00e9nale internationale : un gardien de la justice dans le monde","description":"Le travail de la Cour p\u00e9nale internationale est r\u00e9gi par le statut de Rome, entr\u00e9 en vigueur le 2 juillet 2002.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/fr\/la-cour-penale-internationale-gardien-de-la-justice-dans-le-monde\/","og_locale":"fr_FR","og_type":"article","og_title":"La Corte Penal Internacional: un vigilante de la justicia en el mundo","og_description":"La actuaci\u00f3n de la Corte Penal Internacional est\u00e1 regida por el Estatuto de Roma que entr\u00f3 en rigor el 2 de julio de 2002.","og_url":"https:\/\/venfort.com\/fr\/la-cour-penale-internationale-gardien-de-la-justice-dans-le-monde\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2020-07-23T20:40:00+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/07\/corte-penal-internacional.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"\u00c9crit par":"VENFORT","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"La Corte Penal Internacional: un vigilante de la justicia en el mundo","datePublished":"2020-07-23T20:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/"},"wordCount":1398,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/07\/corte-penal-internacional.jpg","keywords":["Corte Penal Internacional","Derecho Penal","Lesa Humanidad"],"articleSection":["Jurisdicci\u00f3n Internacional"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/","url":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/","name":"La Cour p\u00e9nale internationale : un gardien de la justice dans le monde","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/07\/corte-penal-internacional.jpg","datePublished":"2020-07-23T20:40:00+00:00","description":"Le travail de la Cour p\u00e9nale internationale est r\u00e9gi par le statut de Rome, entr\u00e9 en vigueur le 2 juillet 2002.","breadcrumb":{"@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/07\/corte-penal-internacional.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/07\/corte-penal-internacional.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/la-corte-penal-internacional-vigilante-de-justicia-en-el-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"La Corte Penal Internacional: un vigilante de la justicia en el mundo"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Cabinet : Droit p\u00e9nal \u00e9conomique, droit p\u00e9nal international, droit des soci\u00e9t\u00e9s, droit financier, droit administratif, droit civil et droit des successions internationales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Avocats de Venfort","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/fr\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/comments?post=2466"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media\/2467"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media?parent=2466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/categories?post=2466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/tags?post=2466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}