{"id":2513,"date":"2020-02-20T08:00:00","date_gmt":"2020-02-20T12:00:00","guid":{"rendered":"https:\/\/venfort.com\/blog\/?p=1115"},"modified":"2020-02-20T08:00:00","modified_gmt":"2020-02-20T12:00:00","slug":"reforme-du-code-penal-espagnol","status":"publish","type":"post","link":"https:\/\/venfort.com\/fr\/reforma-del-codigo-penal-espanol\/","title":{"rendered":"La r\u00e9forme du code p\u00e9nal espagnol r\u00e9visera le d\u00e9lit de s\u00e9dition et de r\u00e9bellion."},"content":{"rendered":"<p>Le code p\u00e9nal est l'instrument juridique et fondamental dans lequel sont envisag\u00e9es les normes de fond qui prot\u00e8gent les biens juridiques de la nation et de l'\u00c9tat, c'est-\u00e0-dire qu'en plus de contenir les normes punitives et de sp\u00e9cifier les responsabilit\u00e9s p\u00e9nales qui doivent \u00eatre assum\u00e9es par ceux qui commettent l'un des crimes typifi\u00e9s, son objet principal est la protection de ces biens.\u00a0<\/p>\n\n\n\n<p>Ses r\u00e9formes sont principalement dues au principe de progressivit\u00e9, c'est-\u00e0-dire que de temps en temps, les pays doivent revoir et \u00e9valuer ce cadre r\u00e9glementaire, dans l'intention de l'adapter \u00e0 leur r\u00e9alit\u00e9 et aux engagements juridiques internationaux qu'ils ont sign\u00e9s.<\/p>\n\n\n\n<p><strong>En Espagne, l'initiative de r\u00e9forme a \u00e9t\u00e9 propos\u00e9e par le pouvoir ex\u00e9cutif.<\/strong> et en tant que priorit\u00e9 parall\u00e8lement \u00e0 la nouvelle loi sur l'\u00e9ducation.<\/p>\n\n\n\n<p>Son pr\u00e9sident, Pedro S\u00e1nchez, a affirm\u00e9 que le code p\u00e9nal n'\u00e9tait pas adapt\u00e9 \u00e0 l'\u00e9poque que traverse la nation et que, par exemple, il n'envisageait pas des crimes comparables \u00e0 ceux qui se produisent dans le reste de l'Europe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Controverse autour du projet de r\u00e9forme du code p\u00e9nal espagnol<\/h2>\n\n\n\n<p><strong>Parmi les aspects propos\u00e9s dans la r\u00e9vision qui ont suscit\u00e9 le plus de controverse figure la r\u00e9forme des crimes de s\u00e9dition et de r\u00e9bellion.<\/strong>, compte tenu du fait que ce changement pourrait r\u00e9duire consid\u00e9rablement la peine impos\u00e9e par la Cour supr\u00eame espagnole en octobre 2019 aux dirigeants de l'affaire Proc\u00e9s pour s\u00e9dition et d\u00e9tournement de fonds publics. La r\u00e9duction des charges appliqu\u00e9es pourrait \u00eatre efficace en raison du principe de l'indubio pro reo, qui applique exceptionnellement la r\u00e9troactivit\u00e9 de la loi p\u00e9nale lorsqu'elle est plus favorable \u00e0 l'accus\u00e9. Il est \u00e9galement consid\u00e9r\u00e9 qu'en r\u00e9duisant les peines pour la s\u00e9dition, le d\u00e9tournement de fonds deviendra le principal d\u00e9lit de d\u00e9ch\u00e9ance de la fonction publique.<\/p>\n\n\n\n<p><a href=\"https:\/\/venfort.com\/fr\/blog\/le-crime-de-sedition-et-de-rebellion-differences\/#.XkqVUfR7nIU\">La s\u00e9dition est \u00e9rig\u00e9e en infraction p\u00e9nale \u00e0 l'article 544 du code p\u00e9nal en vigueur.<\/a> comme un d\u00e9lit de trouble \u00e0 l'ordre public. Elle pr\u00e9voit la punition de ceux qui se soul\u00e8vent publiquement et de mani\u00e8re tumultueuse pour entraver, par la force ou en dehors des m\u00e9canismes l\u00e9gaux, l'application de mesures ou l'exercice l\u00e9gitime des fonctions d'un fonctionnaire public. La s\u00e9dition est passible d'une peine de quatre \u00e0 huit ans d'emprisonnement.<strong> <\/strong>l'emprisonnement, qui peut aller jusqu'\u00e0 10 ans pour les dirigeants ou 15 ans pour les autorit\u00e9s qui se livrent \u00e0 de telles actions.<\/p>\n\n\n\n<p><strong>D'autre part, la r\u00e9forme semble inclure une \u00e9valuation du crime de r\u00e9bellion<\/strong> de durcir leur peine. Jusqu'\u00e0 pr\u00e9sent, les personnes condamn\u00e9es pour r\u00e9bellion encourent une peine maximale de 25 ans de prison. Pour \u00eatre identifi\u00e9, il faut prouver l'usage de la violence affectant autrui ou le patrimoine national.<\/p>\n\n\n\n<p><strong>Il n'y a pas encore de proposition claire sur les aspects du code qui pourraient \u00eatre modifi\u00e9s.<\/strong>, La question en est encore au stade initial de la discussion. Plusieurs secteurs, tels que la libert\u00e9 de communication et la libert\u00e9 de la presse, se sont joints \u00e0 l'initiative dans l'intention d'adapter le cadre juridique p\u00e9nal aux situations v\u00e9cues dans le pays sur ces questions.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Chez Alan Aldana &amp; Abogados, nos sp\u00e9cialistes en droit p\u00e9nal sont favorables \u00e0 des r\u00e9formes qui vont toujours dans le sens de la protection et de la sauvegarde des biens juridiques et qui s'adaptent avec une juste proportionnalit\u00e9 et dosim\u00e9trie aux exigences de la soci\u00e9t\u00e9.<\/strong><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Sources consult\u00e9es :<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li><a rel=\"noreferrer noopener\" aria-label=\"mundo.sputniknews.com (ouvre un nouvel onglet)\" href=\"https:\/\/mundo.sputniknews.com\/espana\/202002171090500599-espana-reforma-el-codigo-penal-favorecera-a-los-condenados-por-el-proces-catalan\/\" target=\"_blank\">world.sputniknews.com<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"elpais.com (ouvre un nouvel onglet)\" href=\"https:\/\/elpais.com\/politica\/2020\/01\/21\/actualidad\/1579596514_221447.html\" target=\"_blank\">elpais.com<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"lavanguardia.com (ouvre un nouvel onglet)\" href=\"https:\/\/www.lavanguardia.com\/vida\/20200213\/473530022889\/entidades-internacionales-y-juristas-reclaman-a-espana-la-reforma-del-codigo-penal-en-materia-de-libertad-de-expresion.html\" target=\"_blank\">lavanguardia.com<\/a><\/li><li><a rel=\"noreferrer noopener\" aria-label=\"elmundo.es (ouvre un nouvel onglet)\" href=\"https:\/\/www.elmundo.es\/espana\/2020\/01\/21\/5e27040a21efa07b1e8b4604.html\" target=\"_blank\">elmundo.es<\/a><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>El C\u00f3digo Penal es el instrumento legal y fundamental en el que se contemplan las normas sustantivas que protegen los bienes jur\u00eddicos de la naci\u00f3n y el Estado, es decir, adem\u00e1s de contener las normas punitivas y especificar las responsabilidades penales que deben asumir quienes incurran en alguno de los delitos tipificados, su objeto principal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2514,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[29],"tags":[79,125],"class_list":["post-2513","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ejercicio-profesional","tag-derecho-penal","tag-espana","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3digo Penal espa\u00f1ol: reforma que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n<\/title>\n<meta name=\"description\" content=\"Abordamos en este post nuestra mirada sobre la propuesta de reforma del c\u00f3digo penal espa\u00f1ol que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/fr\/reforme-du-code-penal-espagnol\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3digo Penal espa\u00f1ol: reforma que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Abordamos en este post nuestra mirada sobre la propuesta de reforma del c\u00f3digo penal espa\u00f1ol que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/fr\/reforme-du-code-penal-espagnol\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-20T12:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2020\/02\/codigo-penal-espanol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"Reforma del C\u00f3digo Penal espa\u00f1ol revisar\u00e1 delito de sedici\u00f3n y rebeli\u00f3n\",\"datePublished\":\"2020-02-20T12:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/\"},\"wordCount\":637,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/codigo-penal-espanol.jpg\",\"keywords\":[\"Derecho Penal\",\"Espa\u00f1a\"],\"articleSection\":[\"Ejercicio Profesional\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/\",\"name\":\"C\u00f3digo Penal espa\u00f1ol: reforma que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/codigo-penal-espanol.jpg\",\"datePublished\":\"2020-02-20T12:00:00+00:00\",\"description\":\"Abordamos en este post nuestra mirada sobre la propuesta de reforma del c\u00f3digo penal espa\u00f1ol que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/codigo-penal-espanol.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/codigo-penal-espanol.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/reforma-del-codigo-penal-espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reforma del C\u00f3digo Penal espa\u00f1ol revisar\u00e1 delito de sedici\u00f3n y rebeli\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/fr\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Code p\u00e9nal espagnol : r\u00e9forme du d\u00e9lit de s\u00e9dition et de r\u00e9bellion","description":"Dans ce billet, nous examinons le projet de r\u00e9forme du code p\u00e9nal espagnol qui r\u00e9visera le d\u00e9lit de s\u00e9dition et de r\u00e9bellion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/fr\/reforme-du-code-penal-espagnol\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f3digo Penal espa\u00f1ol: reforma que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n","og_description":"Abordamos en este post nuestra mirada sobre la propuesta de reforma del c\u00f3digo penal espa\u00f1ol que revisar\u00e1 el delito de sedici\u00f3n y rebeli\u00f3n","og_url":"https:\/\/venfort.com\/fr\/reforme-du-code-penal-espagnol\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2020-02-20T12:00:00+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/02\/codigo-penal-espanol.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"\u00c9crit par":"VENFORT","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"Reforma del C\u00f3digo Penal espa\u00f1ol revisar\u00e1 delito de sedici\u00f3n y rebeli\u00f3n","datePublished":"2020-02-20T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/"},"wordCount":637,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/02\/codigo-penal-espanol.jpg","keywords":["Derecho Penal","Espa\u00f1a"],"articleSection":["Ejercicio Profesional"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/","url":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/","name":"Code p\u00e9nal espagnol : r\u00e9forme du d\u00e9lit de s\u00e9dition et de r\u00e9bellion","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/02\/codigo-penal-espanol.jpg","datePublished":"2020-02-20T12:00:00+00:00","description":"Dans ce billet, nous examinons le projet de r\u00e9forme du code p\u00e9nal espagnol qui r\u00e9visera le d\u00e9lit de s\u00e9dition et de r\u00e9bellion.","breadcrumb":{"@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/02\/codigo-penal-espanol.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/02\/codigo-penal-espanol.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/reforma-del-codigo-penal-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"Reforma del C\u00f3digo Penal espa\u00f1ol revisar\u00e1 delito de sedici\u00f3n y rebeli\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Cabinet : Droit p\u00e9nal \u00e9conomique, droit p\u00e9nal international, droit des soci\u00e9t\u00e9s, droit financier, droit administratif, droit civil et droit des successions internationales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Avocats de Venfort","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/fr\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/comments?post=2513"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media\/2514"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media?parent=2513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/categories?post=2513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/tags?post=2513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}