{"id":2524,"date":"2020-01-16T08:00:00","date_gmt":"2020-01-16T12:00:00","guid":{"rendered":"https:\/\/venfort.com\/blog\/?p=1092"},"modified":"2020-01-16T08:00:00","modified_gmt":"2020-01-16T12:00:00","slug":"lethique-grands-delits-sujets-les-plus-lus-2019","status":"publish","type":"post","link":"https:\/\/venfort.com\/fr\/la-etica-grandes-delitos-temas-mas-leidos-2019\/","title":{"rendered":"L'\u00e9thique et les grands crimes qui touchent le monde ont \u00e9t\u00e9 les sujets les plus lus en 2019"},"content":{"rendered":"<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>L'ann\u00e9e commence et c'est un bon moment pour revoir les sujets qui ont marqu\u00e9 notre quotidien, afin de nous fixer de nouveaux objectifs pour 2020. Chez Alan Aldana &amp; Abogados, nous avons fait l'exercice de nous souvenir des articles de notre blog les plus lus en 2019 et nous avons s\u00e9lectionn\u00e9 les 10 textes qui ont re\u00e7u le plus d'attention.<\/p><\/blockquote>\n\n\n\n<p><strong>La d\u00e9ontologie du professionnel du droit reste un sujet important pour ceux qui nous rendent visite.<\/strong>. Cet int\u00e9r\u00eat pour les bonnes pratiques est, sans aucun doute, une preuve de la pertinence qu'a l'exercice \u00e9thique et conforme aux principes. Il peut m\u00eame donner une id\u00e9e du chemin que la profession est en train d'emprunter.<\/p>\n\n\n\n<p><strong>Les th\u00e8mes <\/strong>li\u00e9s \u00e0 des m\u00e9canismes juridiques \u00e9tablis au Venezuela ont suscit\u00e9 un grand int\u00e9r\u00eat. Dans ce sens, on peut citer la r\u00e9glementation contre la cybercriminalit\u00e9, le principe de proportionnalit\u00e9 des peines dans le syst\u00e8me juridique et le contr\u00f4le des changes \u00e9tabli dans le pays.<\/p>\n\n\n\n<p><strong>La d\u00e9finition du terme crise humanitaire, ses caract\u00e9ristiques et les m\u00e9canismes pour la proclamer<\/strong>, a \u00e9t\u00e9 l'un des sujets les plus pertinents cette ann\u00e9e. Notre liste comprenait \u00e9galement le post relatif aux implications du d\u00e9lit de blanchiment d'argent, ainsi que les caract\u00e9ristiques fondamentales du processus d'extradition.<\/p>\n\n\n\n<p>De plus, nos lecteurs ont \u00e9t\u00e9 r\u00e9ceptifs aux informations li\u00e9es \u00e0 l'application pratique de la profession et se sont int\u00e9ress\u00e9s \u00e0 en savoir plus sur les tendances des services juridiques et les recommandations cl\u00e9s pour r\u00e9ussir un entretien d'embauche dans un cabinet d'avocats.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Voici notre liste des 10 sujets les plus lus sur le blog du cabinet en 2019 :<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"http:\/\/aldanayabogados.com\/blog\/etica-deontologia-abogado-venezolano\/#.XfeKgBvB_IU\">Le chemin \u00e9thique de l'avocat v\u00e9n\u00e9zu\u00e9lien. Consid\u00e9rations g\u00e9n\u00e9rales\u00a0<\/a><\/h3>\n\n\n\n<p><strong>La moralit\u00e9 professionnelle montre la voie \u00e0 suivre pour toute personne qualifi\u00e9e.<\/strong> dans un domaine d\u00e9termin\u00e9. Pour se conformer l\u00e9galement et \u00e9thiquement \u00e0 son action dans la vie professionnelle. L'\u00e9tude des devoirs moraux d'un professionnel s'appelle la d\u00e9ontologie et, dans ce cas, met en \u00e9vidence les connaissances n\u00e9cessaires pour \u00eatre avocat.<\/p>\n\n\n\n<p>Au Venezuela, le<a href=\"http:\/\/abogadoszulia.org.ve\/wp-content\/uploads\/2015\/04\/etica.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (s&#039;ouvre dans un nouvel onglet)\"> Code d'\u00e9thique professionnelle des avocats<\/a> Le respect des r\u00e8glements est obligatoire pour tous ceux qui ont les capacit\u00e9s acad\u00e9miques pour exercer la profession. La probit\u00e9, l'honn\u00eatet\u00e9, la discr\u00e9tion, l'efficacit\u00e9, le d\u00e9sint\u00e9ressement, la v\u00e9racit\u00e9 et la loyaut\u00e9 sont des exigences fondamentales pour l'exercice professionnel. De m\u00eame, il est entendu que l'avocat doit conserver son ind\u00e9pendance dans son travail en n'acceptant aucune suggestion de son repr\u00e9sent\u00e9 ou patronn\u00e9 pour porter atteinte \u00e0 son int\u00e9grit\u00e9 et \u00e0 sa dignit\u00e9 professionnelles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"http:\/\/aldanayabogados.com\/blog\/crisis-humanitaria-significado\/#.XfeK-RvB_IU\">2. Crise humanitaire : que signifie-t-elle ?\u00a0<\/a><\/h3>\n\n\n\n<p><strong>Selon les Nations Unies<\/strong>, Une crise humanitaire est li\u00e9e \u00e0 des situations d'urgence r\u00e9sultant de catastrophes, qu'il s'agisse d'\u00e9v\u00e9nements naturels - tremblements de terre, inondations et temp\u00eates - ou de conflits arm\u00e9s de haute intensit\u00e9 qui mettent en danger la vie d'un nombre consid\u00e9rable de personnes.<\/p>\n\n\n\n<p>Tout au long de l'histoire, il y a eu de profondes crises humanitaires. L'une des plus importantes a eu lieu en 1991. Lorsque la R\u00e9publique f\u00e9d\u00e9rale de Somalie a \u00e9t\u00e9 frapp\u00e9e par une s\u00e9rie d'attentats \u00e0 la bombe.<a href=\"http:\/\/aldanayabogados.com\/blog\/justicia-transicional-libertad-equidad\/\"> \u00e9v\u00e9nements conflictuels<\/a> probl\u00e8mes politiques et socio-\u00e9conomiques, cons\u00e9quence de la lutte entre les diff\u00e9rentes factions pour le pouvoir dans le pays africain.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/loi-speciale-contre-la-criminalite-informatique\/#.XfeLHBvB_IU\">3. Aspects g\u00e9n\u00e9raux de la loi sp\u00e9ciale contre les d\u00e9lits informatiques au Venezuela\u00a0<\/a><\/h3>\n\n\n\n<p><strong>La Loi Sp\u00e9ciale contre les Infractions Informatiques<\/strong> a \u00e9t\u00e9 publi\u00e9 au Journal officiel n\u00b0 37.313 du 30 octobre 2001 et est officiellement entr\u00e9 en vigueur le 30 novembre 2001. L'objectif de cet instrument juridique est la protection compl\u00e8te des syst\u00e8mes utilisant les technologies de l'information, ainsi que la pr\u00e9vention et la r\u00e9pression des d\u00e9lits commis contre ces syst\u00e8mes, l'un de leurs composants, ou des d\u00e9lits commis par l'utilisation de ces technologies.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/principe-de-proportionnalite-sanctions-systeme-penal-venezuelien\/#.XfeMRxvB_IU\">4. Le principe de proportionnalit\u00e9 des peines comme outil de dosage dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien\u00a0<\/a><\/h3>\n\n\n\n<p><strong>L'administration de la justice implique d'attribuer quelle est la mani\u00e8re de payer<\/strong> pour chaque acte commis, ce qui n'est g\u00e9n\u00e9ralement pas une t\u00e2che facile et qui n\u00e9cessite l'\u00e9valuation du principe de proportionnalit\u00e9 des peines, afin de d\u00e9terminer si elles sont excessives ou non en fonction du d\u00e9lit commis.<\/p>\n\n\n\n<p><strong>Le mod\u00e8le l\u00e9gal d\u00e9mocratique et de droit \u00e9tabli au Venezuela<\/strong> parier sur la mod\u00e9ration dans la proportionnalit\u00e9 des peines en tenant compte du degr\u00e9 d'atteinte du bien juridique pour leur application. En ce sens, le calcul de la peine s'effectue selon des crit\u00e8res objectifs et subjectifs gr\u00e2ce auxquels il est possible de peser et d'\u00e9valuer le caract\u00e8re illicite de toutes les limites normatives des libert\u00e9s, ainsi que de l'application de la l\u00e9galit\u00e9 qui restreint leur exercice. Le primordial dans l'application des peines est d'\u00e9viter les d\u00e9lits majeurs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/entrevista-exitosa-en-un-bufete\/#.Xffk_xtZ21s\">5. Pr\u00e9parez-vous \u00e0 votre premier entretien r\u00e9ussi dans un cabinet d'avocats\u00a0<\/a><\/h3>\n\n\n\n<p><strong>Bien que toutes les professions et occupations n\u00e9cessitent du talent humain<\/strong> form\u00e9 pour travailler sous pression, en droit les professionnels doivent faire preuve d'une capacit\u00e9 de r\u00e9ponse et de communication efficace et rapide. La premi\u00e8re \u00e9tape pour r\u00e9ussir un entretien dans un cabinet d'avocats commence avant la rencontre en personne.<a href=\"http:\/\/www.tendencias21.net\/Saber-elaborar-un-buen-curriculum-es-garantia-en-las-entrevistas-de-trabajo_a11294.html\"> Le curriculum vitae<\/a> offre des informations pr\u00e9cieuses sur votre exp\u00e9rience et vos capacit\u00e9s, elle doit donc \u00eatre r\u00e9dig\u00e9e honn\u00eatement et con\u00e7ue de mani\u00e8re attrayante<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/le-blanchiment-dargent-a-des-implications\/\">La l\u00e9gitimation du capital a diff\u00e9rentes implications juridiques dans le monde.<\/a>\u00a0<\/h3>\n\n\n\n<p><strong>Le blanchiment d'argent laisse toujours des traces<\/strong> et ceci est d\u00e9couvert t\u00f4t ou tard, divers pays entreprennent des actions pour combattre la criminalit\u00e9. L'Office des Nations Unies contre la Drogue et le Crime (ONUDC) a \u00e9t\u00e9 l'une des institutions qui a entrepris la lutte contre la criminalit\u00e9 internationale, o\u00f9 la l\u00e9gitimation de capitaux ou le blanchiment d'argent est fr\u00e9quemment impliqu\u00e9.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/processus-dextradition\/#.XffmSxtZ21s\">7. Proc\u00e9dure d'extradition : caract\u00e9ristiques fondamentales pour comprendre sa port\u00e9e<\/a>&nbsp;<\/h3>\n\n\n\n<p><strong>L'extradition est une proc\u00e9dure judiciaire par laquelle un \u00c9tat pr\u00e9sente une demande d'extradition.<\/strong> de retour d'une personne mise en cause pour un d\u00e9lit, qui a \u00e9t\u00e9 emprisonn\u00e9e dans un autre pays \u00e0 la suite d'un mandat d'arr\u00eat international, dans le but de la juger ou de continuer la peine d\u00e9j\u00e0 prononc\u00e9e. Elle est r\u00e9glement\u00e9e par des trait\u00e9s internationaux et par les lois de chaque pays, car pour \u00eatre effective, elle n\u00e9cessite la signature de conventions internationales qui prot\u00e8gent cette figure entre les nations impliqu\u00e9es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/petition-de-la-commission-interamericaine\/#.XffmrBtZ21s\">8. Une requ\u00eate \u00e0 la Commission interam\u00e9ricaine : comment faire valoir les Droits de l'Homme ?\u00a0<\/a><\/h3>\n\n\n\n<p><strong><a href=\"http:\/\/aldanayabogados.com\/blog\/sistema-interamericano-derechos-humanos\/#.WhLcc9LibIU\">Le syst\u00e8me interam\u00e9ricain<\/a> de Derechos Humanos est une instance garante<\/strong> des droits de l'homme sur le continent am\u00e9ricain, c'est pourquoi conna\u00eetre sa comp\u00e9tence en profondeur est tr\u00e8s utile. Ce syst\u00e8me est n\u00e9 de la difficile exp\u00e9rience de l'humanit\u00e9 dans divers conflits arm\u00e9s, o\u00f9 les garanties fondamentales ont \u00e9t\u00e9 syst\u00e9matiquement et profond\u00e9ment viol\u00e9es. Son intention est de promouvoir la protection r\u00e9gionale des droits de l'homme en toutes circonstances.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/tendances-dans-les-services-juridiques\/#.XffnUxtZ21s\">9. L'expansion et l'essor technologique sont les tendances des services juridiques pour 2019\u00a0<\/a><\/h3>\n\n\n\n<p><strong>Lever <a href=\"http:\/\/aldanayabogados.com\/blog\/bufetes-tecnologia\/\">en innovation technologique<\/a> est l'une des t\u00e2ches que les services juridiques doivent s'efforcer d'accomplir.<\/strong>, car, c'est ce qui leur permettra de rester en vie et d'atteindre l'efficacit\u00e9 dans le secteur d'ici 2019. L'utilisation de ces technologies offrira la possibilit\u00e9 de g\u00e9rer davantage de donn\u00e9es et de trouver les meilleures fa\u00e7ons de prot\u00e9ger ces informations confidentielles. Pour y parvenir efficacement, il est essentiel de faire appel \u00e0 l'avis d'experts dans le domaine, car les programmes appropri\u00e9s peuvent automatiser les processus juridiques qui s'y pr\u00eatent.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/venfort.com\/fr\/blog\/controle-des-changes-au-venezuela\/\">10. Le contr\u00f4le des changes et ses effets pendant 15 ans au Venezuela&nbsp;<\/a><\/h3>\n\n\n\n<p><strong>La restriction \u00e0 la libre convertibilit\u00e9 de la monnaie a commenc\u00e9 \u00e0 s'appliquer au Venezuela<\/strong> en 2003 et depuis lors, la r\u00e9glementation a chang\u00e9 au fil des ans. La r\u00e9glementation juridique des changes relative \u00e0 la circulation, \u00e0 la conversion et \u00e0 l'\u00e9valuation de la monnaie trouve son origine dans des actes sous-l\u00e9gaux qui soutiennent le r\u00e9gime de gestion des devises bas\u00e9 sur : la vente obligatoire de devises au BCV r\u00e9sultant des exportations, des prestations de services et des fournitures technologiques ; et du syst\u00e8me de vente de devises \u00e0 ceux qui le demandent, aux agents \u00e9conomiques priv\u00e9s et aux organismes priv\u00e9s qui le demandent.<\/p>","protected":false},"excerpt":{"rendered":"<p>Estamos abriendo el a\u00f1o y es un buen momento para repasar aquellos temas que estuvieron presentes en nuestra cotidianidad, con la intenci\u00f3n de plantearnos nuevas metas para 2020. En Alan Aldana &amp; Abogados hicimos el ejercicio de recordar aquellos art\u00edculos de nuestro blog m\u00e1s le\u00eddos durante 2019 y seleccionamos los 10 textos que obtuvieron mayor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2525,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[27],"tags":[53,243,91],"class_list":["post-2524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bufete","tag-abogados","tag-etica","tag-tendencias","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La \u00e9tica y los grandes delitos fueron los temas m\u00e1s le\u00eddos en 2019<\/title>\n<meta name=\"description\" content=\"La \u00e9tica del profesional del Derecho sigue siendo un tema importante para quienes nos visitan. En este art\u00edculo el top ten de lo m\u00e1s l\u00e9ido.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/fr\/lethique-grands-delits-sujets-les-plus-lus-2019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La \u00e9tica y los grandes delitos fueron los temas m\u00e1s le\u00eddos en 2019\" \/>\n<meta property=\"og:description\" content=\"La \u00e9tica del profesional del Derecho sigue siendo un tema importante para quienes nos visitan. En este art\u00edculo el top ten de lo m\u00e1s l\u00e9ido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/fr\/lethique-grands-delits-sujets-les-plus-lus-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-16T12:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/la-etica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"La \u00e9tica y los grandes delitos que afectan al mundo fueron los temas m\u00e1s le\u00eddos en 2019\",\"datePublished\":\"2020-01-16T12:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/\"},\"wordCount\":1440,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/la-etica.jpg\",\"keywords\":[\"Abogados\",\"\u00e9tica\",\"Tendencias\"],\"articleSection\":[\"Bufete\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/\",\"name\":\"La \u00e9tica y los grandes delitos fueron los temas m\u00e1s le\u00eddos en 2019\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/la-etica.jpg\",\"datePublished\":\"2020-01-16T12:00:00+00:00\",\"description\":\"La \u00e9tica del profesional del Derecho sigue siendo un tema importante para quienes nos visitan. En este art\u00edculo el top ten de lo m\u00e1s l\u00e9ido.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/la-etica.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/la-etica.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/la-etica-grandes-delitos-temas-mas-leidos-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La \u00e9tica y los grandes delitos que afectan al mundo fueron los temas m\u00e1s le\u00eddos en 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/fr\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'\u00e9thique et les grands crimes ont \u00e9t\u00e9 les th\u00e8mes les plus lus en 2019","description":"L'\u00e9thique du professionnel du droit reste un sujet important pour nos visiteurs. Dans cet article, le top dix des lectures les plus populaires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/fr\/lethique-grands-delits-sujets-les-plus-lus-2019\/","og_locale":"fr_FR","og_type":"article","og_title":"La \u00e9tica y los grandes delitos fueron los temas m\u00e1s le\u00eddos en 2019","og_description":"La \u00e9tica del profesional del Derecho sigue siendo un tema importante para quienes nos visitan. En este art\u00edculo el top ten de lo m\u00e1s l\u00e9ido.","og_url":"https:\/\/venfort.com\/fr\/lethique-grands-delits-sujets-les-plus-lus-2019\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2020-01-16T12:00:00+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/la-etica.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"\u00c9crit par":"VENFORT","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"La \u00e9tica y los grandes delitos que afectan al mundo fueron los temas m\u00e1s le\u00eddos en 2019","datePublished":"2020-01-16T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/"},"wordCount":1440,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/la-etica.jpg","keywords":["Abogados","\u00e9tica","Tendencias"],"articleSection":["Bufete"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/","url":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/","name":"L'\u00e9thique et les grands crimes ont \u00e9t\u00e9 les th\u00e8mes les plus lus en 2019","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/la-etica.jpg","datePublished":"2020-01-16T12:00:00+00:00","description":"L'\u00e9thique du professionnel du droit reste un sujet important pour nos visiteurs. Dans cet article, le top dix des lectures les plus populaires.","breadcrumb":{"@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/la-etica.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2020\/01\/la-etica.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/la-etica-grandes-delitos-temas-mas-leidos-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"La \u00e9tica y los grandes delitos que afectan al mundo fueron los temas m\u00e1s le\u00eddos en 2019"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Cabinet : Droit p\u00e9nal \u00e9conomique, droit p\u00e9nal international, droit des soci\u00e9t\u00e9s, droit financier, droit administratif, droit civil et droit des successions internationales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Avocats de Venfort","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/fr\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/comments?post=2524"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media\/2525"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media?parent=2524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/categories?post=2524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/tags?post=2524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}