{"id":2658,"date":"2018-10-04T08:00:13","date_gmt":"2018-10-04T12:00:13","guid":{"rendered":"https:\/\/venfort.com\/?p=771"},"modified":"2018-10-04T08:00:13","modified_gmt":"2018-10-04T12:00:13","slug":"principe-de-proportionnalite-sanctions-systeme-penal-venezuelien","status":"publish","type":"post","link":"https:\/\/venfort.com\/fr\/principio-proporcionalidad-penas-sistema-penal-venezolano\/","title":{"rendered":"Le principe de proportionnalit\u00e9 des peines comme outil dosim\u00e9trique dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien"},"content":{"rendered":"<h4 class=\"wp-block-heading\">Article r\u00e9f\u00e9renc\u00e9 r\u00e9dig\u00e9 par Eduardo Mora Rodr\u00edguez<\/h4>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Depuis que les civilisations se sont form\u00e9es, l'application de la justice a \u00e9t\u00e9 un m\u00e9canisme de contr\u00f4le social et, depuis cette \u00e9poque jusqu'\u00e0 nos jours, les syst\u00e8mes p\u00e9naux utilis\u00e9s se sont transform\u00e9s. <a href=\"https:\/\/venfort.com\/fr\/haut-commissaire-aux-droits-de-lhomme\/\">La justice doit respecter la dignit\u00e9 humaine<\/a>, le bien commun et la pr\u00e9servation du droit. Selon ces principes fondamentaux de fonctionnement, la justice se r\u00e9f\u00e8re \u00e0 la r\u00e9partition \u00e9quitable des valeurs, des co\u00fbts et des b\u00e9n\u00e9fices des actions humaines entre tous les membres d'une soci\u00e9t\u00e9. Dans le syst\u00e8me p\u00e9nal, ce concept prend toute sa dimension, puisqu'il s'agit d'attribuer \u00e0 chacun ce qui lui est d\u00fb en fonction de ses actes.<br\/><\/p><\/blockquote>\n\n\n\n<p><strong>L'administration de la justice consiste \u00e0 d\u00e9terminer comment payer pour chaque acte commis.<\/strong>, Cette t\u00e2che n'est souvent pas simple. Elle n\u00e9cessite une \u00e9tude et une adaptation \u00e0 la diversit\u00e9 des facteurs qui entrent en jeu dans toute activit\u00e9 humaine, afin de prendre \u00e9galement en compte la signification des dommages caus\u00e9s mat\u00e9riellement ou \u00e0 d'autres \u00eatres. Dans l'application de la justice, les responsables peuvent \u00eatre confront\u00e9s au dilemme de savoir s'il faut consid\u00e9rer que le texte juridique \u00e9crit traite tout le monde de la m\u00eame mani\u00e8re, ou s'il faut ajuster la forme \u00e0 leur juste proportion en termes de pr\u00e9judice.<br\/><\/p>\n\n\n\n<p><strong>En ce sens, il est n\u00e9cessaire d'\u00e9valuer le principe de proportionnalit\u00e9 des sanctions.<\/strong>, L'objectif est de d\u00e9tecter si elles sont excessives ou non par rapport \u00e0 l'infraction commise, \u00e0 travers l'\u00e9tude de la proportionnalit\u00e9 dans l'application des peines, en examinant les crit\u00e8res objectifs et subjectifs qui pr\u00e9valent dans la dosim\u00e9trie p\u00e9nale. La dosim\u00e9trie p\u00e9nale d\u00e9finit l'application du principe de proportionnalit\u00e9 de la peine tant par le l\u00e9gislateur lorsqu'il impose une sanction que par les juges et les tribunaux lorsqu'ils statuent sur un cas particulier.<br\/><\/p>\n\n\n\n<p><strong>L'application du principe de proportionnalit\u00e9 des peines dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien<\/strong> a fait l'objet d'une \u00e9tude de l'avocat Eduardo Mora Rodr\u00edguez, dans le cadre de son travail de fin d'\u00e9tudes \u00e0 l'\u00c9cole nationale des procureurs du minist\u00e8re public. L'objectif de l'\u00e9tude \u00e9tait de d\u00e9terminer si le principe de proportionnalit\u00e9 des peines \u00e9tait respect\u00e9 dans le pays, en v\u00e9rifiant si les peines appliqu\u00e9es correspondaient \u00e0 ce qui \u00e9tait \u00e9tabli d'apr\u00e8s les donn\u00e9es sur le bien juridique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le long chemin du deuil<\/h2>\n\n\n\n<p>Au d\u00e9but, les m\u00e9thodes de punition pour toute infraction pouvaient \u00eatre consid\u00e9r\u00e9es comme barbares et disproportionn\u00e9es. Au d\u00e9but de l'\u00e9tablissement des civilisations, les crimes et d\u00e9lits \u00e9taient consid\u00e9r\u00e9s comme des offenses aux dieux et \u00e9taient donc punis de mani\u00e8re plus s\u00e9v\u00e8re, de peur d'\u00e9veiller la col\u00e8re de la divinit\u00e9. On peut donc en d\u00e9duire que la punition a une origine expiatoire.<br\/><\/p>\n\n\n\n<p><strong>Le passage du temps et l'av\u00e8nement de la modernit\u00e9 ont consid\u00e9rablement transform\u00e9 le syst\u00e8me p\u00e9nal.<\/strong>, Au point qu'il est aujourd'hui possible de discuter de la proportionnalit\u00e9 de la peine, en \u00e9vitant qu'une personne ne re\u00e7oive une peine plus importante que le mal qu'elle a commis. La pratique de la loi du tailleur \u00e9tait la notion la plus ancienne et la plus proche de ce que l'on appelle aujourd'hui la dosim\u00e9trie p\u00e9nale, car elle proposait un syst\u00e8me de justice \u00e9quitable dans lequel les peines impos\u00e9es \u00e9taient identiques ou similaires au d\u00e9lit caus\u00e9, ce qui \u00e9tait projet\u00e9 et r\u00e9duisait consid\u00e9rablement l'application de peines colossales. <br\/><\/p>\n\n\n\n<p><strong>De cette pratique, le droit moderne a r\u00e9cup\u00e9r\u00e9 la notion de d\u00e9termination de l'\u00e9tendue du dommage caus\u00e9 au bien juridique.<\/strong>, Le principe de proportionnalit\u00e9 des peines est le fruit d'une \u00e9volution historique cr\u00e9\u00e9e dans le but de pr\u00e9venir les exc\u00e8s et les abus de l'autorit\u00e9 p\u00e9nale. Le principe de proportionnalit\u00e9 des peines est le fruit d'une \u00e9volution historique cr\u00e9\u00e9e dans le but d'\u00e9viter les exc\u00e8s et de fonder toutes les d\u00e9cisions sur l'\u00e9quilibre et la rationalit\u00e9. L'une des lois r\u00e9gissant ce principe stipule que les mesures restreignant les droits doivent \u00eatre pr\u00e9vues par la loi et que leur ex\u00e9cution ne doit servir qu'un but l\u00e9gitime dans une soci\u00e9t\u00e9 d\u00e9mocratique.<br\/><\/p>\n\n\n\n<p><strong>Il convient de noter que le principe de proportionnalit\u00e9 s'applique au moment de la cr\u00e9ation de l'instrument juridique.<\/strong> De m\u00eame, la pertinence de ce principe est plus grande dans le domaine des mesures de s\u00e9curit\u00e9 que dans celui de la condamnation elle-m\u00eame, et implique que la pr\u00e9vision et l'imposition d'une peine soient effectu\u00e9es en fonction de la dangerosit\u00e9 criminelle du sujet.<br\/><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Affaire du Venezuela, syst\u00e8me p\u00e9nal<\/strong><\/h2>\n\n\n\n<p><strong>Le mod\u00e8le juridique d\u00e9mocratique et l'\u00c9tat de droit \u00e9tablis au Venezuela sont fond\u00e9s sur la proportionnalit\u00e9 et la mod\u00e9ration.<\/strong> des sanctions, en tenant compte du degr\u00e9 d'alt\u00e9ration du bien juridique pour lequel elles sont impos\u00e9es. En ce sens, les peines sont calcul\u00e9es selon des crit\u00e8res objectifs et subjectifs qui permettent de peser et d'\u00e9valuer l'ill\u00e9galit\u00e9 de toutes les limites normatives aux libert\u00e9s, ainsi que l'application de la l\u00e9galit\u00e9 qui en restreint l'exercice. L'objectif premier de la d\u00e9termination de la peine est de pr\u00e9venir les infractions majeures.<br\/><\/p>\n\n\n\n<p><strong>Dans son ouvrage, le professionnel Eduardo Mora Rodr\u00edguez souligne que pour \u00e9viter les exc\u00e8s, le principe de proportionnalit\u00e9 au Venezuela repose sur trois r\u00e8gles :<\/strong> l'ad\u00e9quation (qui fait r\u00e9f\u00e9rence au fait que toute limitation d'un droit doit \u00eatre constitutionnellement justifi\u00e9e), la n\u00e9cessit\u00e9 (afin de qualifier d'injuste toute peine non n\u00e9cessaire) et la proportionnalit\u00e9 au sens strict (toute peine doit \u00eatre fond\u00e9e sur la protection d'un droit l\u00e9gal).<br\/><\/p>\n\n\n\n<p><strong>Il est essentiel de savoir qu'aucune personne ne peut \u00eatre punie pour des actes ou des omissions<\/strong> qui ne sont pas pr\u00e9vues comme des crimes dans les instruments juridiques correspondants. Le principe de proportionnalit\u00e9 de la peine, en plus de canaliser une peine pour l'action criminelle sans affecter plus que ce qui est l\u00e9galement consid\u00e9r\u00e9, est une forme de pr\u00e9vention du crime en offrant \u00e0 l'accus\u00e9 l'opportunit\u00e9 de se soumettre \u00e0 l'\u00e9valuation de sa peine dans la juste mesure, c'est-\u00e0-dire sans g\u00e9n\u00e9rer un dommage plus grand que celui qu'il a caus\u00e9. L'application du principe remplit ainsi une fonction de resocialisation.<br\/><\/p>\n\n\n\n<p><strong>L'analyse de la peine d\u00e9pend de variables objectives et subjectives \u00e9valu\u00e9es par le juge ou les tribunaux.<\/strong>. Parmi les aspects objectifs, on peut prendre en compte le pr\u00e9judice r\u00e9el caus\u00e9 au bien juridique, le degr\u00e9 de danger auquel il a \u00e9t\u00e9 soumis, la densit\u00e9 du dommage effectivement caus\u00e9, les circonstances de l'acte ; tandis que parmi les aspects subjectifs, on peut compter la qualit\u00e9 des motifs d\u00e9terminants, le manque d'\u00e9thique de l'acte, l'\u00e9valuation du comportement criminel ou non du sujet, ainsi que d'autres conditions personnelles de la victime ou de l'auteur qui pourraient \u00eatre li\u00e9es \u00e0 l'affaire.<br\/><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Selon l'\u00e9tude, la dosim\u00e9trie p\u00e9nale au Venezuela a une base jurisprudentielle contraignante dans l'arr\u00eat de la Chambre constitutionnelle, l'arr\u00eat n\u00b0 1859 du 18 d\u00e9cembre 2014, avec le magistrat Juan Jos\u00e9 Mendoza Jover comme rapporteur, qui \u00e9tablit la possibilit\u00e9 d'accorder aux personnes accus\u00e9es de d\u00e9lits de trafic de drogue d'un montant mineur des formules alternatives dans l'ex\u00e9cution de la peine. La th\u00e8se d'Eduardo Mora Rodr\u00edguez soutient que la proportionnalit\u00e9 de la peine au Venezuela a une dimension axiologique (li\u00e9e \u00e0 la th\u00e9orie des valeurs) bas\u00e9e sur les valeurs du mod\u00e8le du syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien, dans lequel la peine doit \u00eatre proportionnelle au dommage caus\u00e9, ce qui ne signifie pas n\u00e9cessairement l'impunit\u00e9. Ce n'est qu'en vertu de ces pr\u00e9ceptes qu'il est possible d'emp\u00eacher l'\u00c9tat d'outrepasser ses pouvoirs et de mettre en place un syst\u00e8me judiciaire plus \u00e9quitable qui garantisse les droits de l'homme.<br\/><\/p><\/blockquote>\n\n\n\n<p><strong>Il est important de souligner qu'en aucun cas la proportionnalit\u00e9 de la sanction n'implique une exon\u00e9ration de responsabilit\u00e9.<\/strong> ni \u00e0 la condamnation pour des raisons de pr\u00e9vention ou de promotion de la resocialisation. Cependant, elle tente de se concentrer sur l'\u00e9valuation opportune et r\u00e9elle du pr\u00e9judice commis. Selon le travail effectu\u00e9 par Eduardo Mora Rodr\u00edguez, le principe de proportionnalit\u00e9 dans l'application des peines dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien est conscient de l'imposition d'une peine en relation avec l'intensit\u00e9 avec laquelle le droit l\u00e9gal a \u00e9t\u00e9 viol\u00e9 ou mis en danger.<br\/><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Il existe un certain nombre de crit\u00e8res d'\u00e9valuation et d'appr\u00e9ciation des preuves afin de d\u00e9terminer la peine requise. Au Venezuela, les aspects suivants sont g\u00e9n\u00e9ralement pris en compte :<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Densit\u00e9 des dommages<\/strong>L'importance du grief est \u00e9valu\u00e9e en fonction du pr\u00e9judice caus\u00e9.<\/li><li><strong>Circonstances<\/strong>L'ex\u00e9cution effective de l'acte punissable.<\/li><li><strong>Modalit\u00e9s de la Commission<\/strong>Elle est directement li\u00e9e aux circonstances de lieu, de temps, de mani\u00e8re et d'occasion de l'infraction.<\/li><li><strong>Degr\u00e9 d'exag\u00e9ration<\/strong>Il s'agit du degr\u00e9 d'agressivit\u00e9 r\u00e9p\u00e9t\u00e9e, disproportionn\u00e9e et exag\u00e9r\u00e9e des actes criminels. Il est consid\u00e9r\u00e9 comme un facteur aggravant de la peine.<\/li><li><strong>Degr\u00e9 d'infraction<\/strong>Il s'agit du degr\u00e9 d'infraction \u00e0 la loi dans l'action p\u00e9nale.<\/li><li><strong>Autre situation de la victime ou de la famille de la victime<\/strong>Les conditions ou le traumatisme caus\u00e9s par la situation criminelle sur la victime et les membres de sa famille.<\/li><li><strong>Qualit\u00e9 des motifs<\/strong>Les motifs qui ont conduit l'auteur \u00e0 commettre le crime.<\/li><li><strong>Penchant criminel<\/strong>Casier judiciaire de l'auteur de l'infraction : il s'agit du casier judiciaire de l'auteur de l'infraction.<\/li><li><strong>Conditions personnelles de l'auteur<\/strong>Facteurs sociaux, \u00e9conomiques, physiques, sanitaires, \u00e9conomiques, sociaux et autres qui peuvent \u00eatre pris en compte dans la d\u00e9termination de la peine.<\/li><\/ul>\n\n\n\n<p><strong>Le principal effet de la proportionnalit\u00e9 de la peine en tant qu'outil du syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien est le suivant<\/strong> est la d\u00e9termination des limites de l'action punitive de l'\u00c9tat en graduant les peines en proportion directe de la contribution de facto \u00e0 l'acte punissable. En ce sens, le pouvoir judiciaire doit proc\u00e9der aux interpr\u00e9tations n\u00e9cessaires pour appr\u00e9cier \u00e9quitablement les preuves.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"text-align:center\"><a href=\"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/Articulo-Arbitrado-Eduardo-Mora-Dosimetria-Penal.pdf\" target=\"_blank\" rel=\"noopener\">T\u00e9l\u00e9chargez l'article complet au format PDF \u00e0 partir de ce lien.<\/a><\/h3>\n\n\n\n<p><strong>Sites connexes :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"http:\/\/escueladefiscales.mp.gob.ve\/site\/\" target=\"_blank\" rel=\"noopener\">\u00c9cole nationale des procureurs<\/a><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo arbitrado escrito por Eduardo Mora Rodr\u00edguez Desde que las civilizaciones comenzaron a formarse la aplicaci\u00f3n de la justicia ha sido un mecanismo de control social y desde ese primer momento hasta la actualidad los sistemas penales usados han sido transformados. La justicia debe respetar a la dignidad humana, el bien com\u00fan y la preservaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","omw_enable_modal_window":"enable","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[23],"tags":[],"class_list":["post-2658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formacion-legal","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Principio de proporcionalidad de las penas en el sistema penal Venezolano<\/title>\n<meta name=\"description\" content=\"Compartimos el art\u00edculo arbitrado escrito por Eduardo Mora Rodr\u00edguez sobre la proporcionalidad de las penas en el sistema penal Venezolano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/fr\/principe-de-proportionnalite-sanctions-systeme-penal-venezuelien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Principio de proporcionalidad de las penas en el sistema penal Venezolano\" \/>\n<meta property=\"og:description\" content=\"Compartimos el art\u00edculo arbitrado escrito por Eduardo Mora Rodr\u00edguez sobre la proporcionalidad de las penas en el sistema penal Venezolano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/fr\/principe-de-proportionnalite-sanctions-systeme-penal-venezuelien\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-04T12:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/dosimetria-sistema-penal-venezuela.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"El principio de proporcionalidad de las penas como herramienta de dosimetr\u00eda en el sistema penal Venezolano\",\"datePublished\":\"2018-10-04T12:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/\"},\"wordCount\":1776,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dosimetria-sistema-penal-venezuela.jpg\",\"articleSection\":[\"Formaci\u00f3n legal\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/\",\"name\":\"Principio de proporcionalidad de las penas en el sistema penal Venezolano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dosimetria-sistema-penal-venezuela.jpg\",\"datePublished\":\"2018-10-04T12:00:13+00:00\",\"description\":\"Compartimos el art\u00edculo arbitrado escrito por Eduardo Mora Rodr\u00edguez sobre la proporcionalidad de las penas en el sistema penal Venezolano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dosimetria-sistema-penal-venezuela.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/dosimetria-sistema-penal-venezuela.jpg\",\"width\":1024,\"height\":687},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/principio-proporcionalidad-penas-sistema-penal-venezolano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El principio de proporcionalidad de las penas como herramienta de dosimetr\u00eda en el sistema penal Venezolano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/fr\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Principe de proportionnalit\u00e9 des peines dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien","description":"Nous partageons l'article r\u00e9dig\u00e9 par Eduardo Mora Rodr\u00edguez sur la proportionnalit\u00e9 des peines dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/fr\/principe-de-proportionnalite-sanctions-systeme-penal-venezuelien\/","og_locale":"fr_FR","og_type":"article","og_title":"Principio de proporcionalidad de las penas en el sistema penal Venezolano","og_description":"Compartimos el art\u00edculo arbitrado escrito por Eduardo Mora Rodr\u00edguez sobre la proporcionalidad de las penas en el sistema penal Venezolano","og_url":"https:\/\/venfort.com\/fr\/principe-de-proportionnalite-sanctions-systeme-penal-venezuelien\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2018-10-04T12:00:13+00:00","og_image":[{"width":1024,"height":687,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/dosimetria-sistema-penal-venezuela.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"\u00c9crit par":"VENFORT","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"El principio de proporcionalidad de las penas como herramienta de dosimetr\u00eda en el sistema penal Venezolano","datePublished":"2018-10-04T12:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/"},"wordCount":1776,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/dosimetria-sistema-penal-venezuela.jpg","articleSection":["Formaci\u00f3n legal"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/","url":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/","name":"Principe de proportionnalit\u00e9 des peines dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/dosimetria-sistema-penal-venezuela.jpg","datePublished":"2018-10-04T12:00:13+00:00","description":"Nous partageons l'article r\u00e9dig\u00e9 par Eduardo Mora Rodr\u00edguez sur la proportionnalit\u00e9 des peines dans le syst\u00e8me p\u00e9nal v\u00e9n\u00e9zu\u00e9lien.","breadcrumb":{"@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/dosimetria-sistema-penal-venezuela.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/10\/dosimetria-sistema-penal-venezuela.jpg","width":1024,"height":687},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/principio-proporcionalidad-penas-sistema-penal-venezolano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"El principio de proporcionalidad de las penas como herramienta de dosimetr\u00eda en el sistema penal Venezolano"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Cabinet : Droit p\u00e9nal \u00e9conomique, droit p\u00e9nal international, droit des soci\u00e9t\u00e9s, droit financier, droit administratif, droit civil et droit des successions internationales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Avocats de Venfort","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/fr\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/comments?post=2658"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media\/2659"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media?parent=2658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/categories?post=2658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/tags?post=2658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}