{"id":2720,"date":"2018-02-15T08:00:35","date_gmt":"2018-02-15T12:00:35","guid":{"rendered":"https:\/\/venfort.com\/?p=467"},"modified":"2018-02-15T08:00:35","modified_gmt":"2018-02-15T12:00:35","slug":"infraction-de-harcelement-sexuel-des-femmes","status":"publish","type":"post","link":"https:\/\/venfort.com\/fr\/delito-de-acoso-sexual-mujeres\/","title":{"rendered":"Le crime de harc\u00e8lement sexuel est une question qui doit \u00eatre trait\u00e9e par le syst\u00e8me judiciaire."},"content":{"rendered":"<blockquote><p>Le professionnalisme n'est pas la seule qualit\u00e9 importante pour qualifier ces espaces dans l'environnement professionnel ou acad\u00e9mique. <a href=\"https:\/\/venfort.com\/fr\/petition-de-la-commission-interamericaine\/\">Respect des droits de l'homme<\/a> dans la relation g\u00e9n\u00e9r\u00e9e est essentielle pour garantir des environnements de travail harmonieux et conformes \u00e0 la l\u00e9gislation.<\/p><\/blockquote>\n<p><strong>L'une des circonstances qui affecte souvent gravement le lieu de travail est la survenance de crimes de harc\u00e8lement sexuel.<\/strong>, Le terme \"d\u00e9lit sexuel\" est d\u00e9fini comme le d\u00e9lit consistant \u00e0 solliciter des faveurs de nature sexuelle pour soi-m\u00eame ou pour des tiers, en compromettant des relations de travail \u00e9tablies, en imposant tacitement une menace de la part d'une figure de pouvoir qui favorise la manipulation de la victime dans l'intention de lui faire accepter un comportement sexuel.<\/p>\n<p><strong>Ce crime implique \u00e9galement une discrimination fond\u00e9e sur le sexe lorsque le sexe de la victime est \u00e9tabli.<\/strong>. Cela inclut tout traitement d\u00e9favorable des femmes, notamment en raison de leur maternit\u00e9 ou de leur grossesse, et toute subordination d'un droit \u00e0 l'acceptation d'une situation qui porte atteinte \u00e0 la dignit\u00e9 d'une personne, ce qui constitue un harc\u00e8lement sexuel.<\/p>\n<h2>La d\u00e9finition du d\u00e9lit de harc\u00e8lement sexuel<\/h2>\n<p><strong>D\u00e9finir une situation de harc\u00e8lement sexuel<\/strong> Il faut tenir compte du fait qu'il s'agit d'un comportement non d\u00e9sir\u00e9, importun et non sollicit\u00e9 de nature sexuelle. Derri\u00e8re cet acte, la personne qui le commet aspire \u00e0 une d\u00e9monstration de pouvoir sur l'autre personne, en la contraignant et en portant atteinte \u00e0 sa dignit\u00e9.<\/p>\n<p><strong>En ce sens, la victime de ce type de crime se sent intimid\u00e9e, humili\u00e9e et constamment menac\u00e9e.<\/strong> parce qu'ils sont conscients que la situation compromet leur s\u00e9jour dans l'espace de travail ou d'\u00e9tudes o\u00f9 se d\u00e9roule l'action. Le harc\u00e8lement sexuel alimente la peur et r\u00e9duit consid\u00e9rablement les performances professionnelles ou acad\u00e9miques.<\/p>\n<p><strong>L'auteur du harc\u00e8lement sexuel peut \u00eatre un coll\u00e8gue, un enseignant, un superviseur, un directeur ou m\u00eame un client.<\/strong> qui insistent pour demander des faveurs sexuelles ou des invitations compromettantes. Ce type d'infraction peut se produire physiquement, verbalement ou non verbalement.<\/p>\n<p><strong>Dans le premier cas, l'infraction est commise par des actions qui permettent un contact physique entre le harceleur et la victime.<\/strong>, Le harc\u00e8lement sexuel peut aller de l'attouchement d'une partie du corps sans le consentement de l'int\u00e9ress\u00e9 \u00e0 des regards suggestifs. Le harc\u00e8lement verbal se r\u00e9f\u00e8re au harc\u00e8lement par le biais de commentaires ou d'insinuations \u00e0 caract\u00e8re sexuel, d'invitations verbales \u00e0 avoir des relations sexuelles ou de l'intention de transformer toutes les conversations professionnelles ou acad\u00e9miques en conversations ouvertement sexuelles, tandis que le harc\u00e8lement non verbal se r\u00e9f\u00e8re \u00e0 l'utilisation de mat\u00e9riel tel que des informations ou des photographies pour engager directement la personne harcel\u00e9e sur le plan sexuel.<\/p>\n<h2>Proc\u00e9dure juridique<\/h2>\n<p><strong>En r\u00e8gle g\u00e9n\u00e9rale, la personne harcel\u00e9e ou un tiers qualifi\u00e9 doit d\u00e9poser une plainte aupr\u00e8s des institutions du travail comp\u00e9tentes.<\/strong> Souvent, une fois l'affaire introduite au sein de l'entreprise ou de l'acad\u00e9mie, la victime est convoqu\u00e9e \u00e0 une r\u00e9union avec les autorit\u00e9s hi\u00e9rarchiquement les plus repr\u00e9sentatives afin de pr\u00e9senter la situation et les preuves n\u00e9cessaires.<\/p>\n<p><strong>La plainte doit ensuite faire l'objet d'une enqu\u00eate par le biais de l'\u00e9valuation des preuves et de l'audition des t\u00e9moins,<\/strong> l'examen de documents confidentiels pr\u00e9sentant un int\u00e9r\u00eat, entre autres outils. De m\u00eame, un entretien sera men\u00e9 avec l'accus\u00e9, afin de d\u00e9terminer les responsabilit\u00e9s. Si l'accusation s'av\u00e8re fond\u00e9e, diverses mesures peuvent \u00eatre prises, y compris la suspension de la fonction et l'emprisonnement, le cas \u00e9ch\u00e9ant.<\/p>\n<p><strong>L'Organisation des Nations unies (ONU)<\/strong> <a href=\"http:\/\/www.unwomen.org\/es\/news\/stories\/2017\/11\/press-release-25-november\" target=\"_blank\" rel=\"noopener\">organise diverses activit\u00e9s<\/a> afin de sensibiliser le public \u00e0 ce probl\u00e8me qui, historiquement, touche davantage les femmes que les hommes.<\/p>\n<p><strong>Sources consult\u00e9es :<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/cadenaser.com\/ser\/2018\/01\/16\/tribunales\/1516107074_034895.html\" target=\"_blank\" rel=\"noopener\">Cadenaser.com<\/a><\/li>\n<li><a href=\"http:\/\/www.tuabogadodefensor.com\/acoso-sexual-laboral\/\" target=\"_blank\" rel=\"noopener\">yourlawyerdefender.com<\/a><\/li>\n<li><a href=\"http:\/\/www.unwomen.org\/es\/news\/stories\/2017\/11\/press-release-25-november\" target=\"_blank\" rel=\"noopener\">unwomen.org<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>En el \u00e1mbito laboral o acad\u00e9mico el profesionalismo no es la \u00fanica cualidad importante para calificar estos espacios. El respeto a los derechos humanos en la relaci\u00f3n generada es fundamental para garantizar ambientes laborales armoniosos y en cumplimiento de la ley. Una de las circunstancias que suele afectar los espacios laborales gravemente es la ocurrencia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2721,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[29,311],"tags":[199,229,95],"class_list":["post-2720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ejercicio-profesional","category-sin-categoria","tag-acoso-sexual","tag-consideraciones-legales","tag-derechos-humanos","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El delito de acoso sexual es un tema a atender por la justicia<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo se define el delito de acoso sexual? En este art\u00edculo queremos abordar este importante tema que est\u00e1 en la conversaci\u00f3n mundial y que es un pendiente de la justicia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venfort.com\/fr\/infraction-de-harcelement-sexuel-des-femmes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El delito de acoso sexual es un tema a atender por la justicia\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo se define el delito de acoso sexual? En este art\u00edculo queremos abordar este importante tema que est\u00e1 en la conversaci\u00f3n mundial y que es un pendiente de la justicia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venfort.com\/fr\/infraction-de-harcelement-sexuel-des-femmes\/\" \/>\n<meta property=\"og:site_name\" content=\"Venfort\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/venfortyabogados\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-15T12:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venfort.com\/wp-content\/uploads\/2018\/02\/delito-de-acoso-sexual.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"VENFORT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:site\" content=\"@Venfortabogados\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"VENFORT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/\"},\"author\":{\"name\":\"VENFORT\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\"},\"headline\":\"El delito de acoso sexual es un tema a atender por la justicia\",\"datePublished\":\"2018-02-15T12:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/\"},\"wordCount\":652,\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/delito-de-acoso-sexual.jpg\",\"keywords\":[\"acoso sexual\",\"Consideraciones Legales\",\"Derechos Humanos\"],\"articleSection\":[\"Ejercicio Profesional\",\"Sin categor\u00eda\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/\",\"name\":\"El delito de acoso sexual es un tema a atender por la justicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/delito-de-acoso-sexual.jpg\",\"datePublished\":\"2018-02-15T12:00:35+00:00\",\"description\":\"\u00bfC\u00f3mo se define el delito de acoso sexual? En este art\u00edculo queremos abordar este importante tema que est\u00e1 en la conversaci\u00f3n mundial y que es un pendiente de la justicia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/delito-de-acoso-sexual.jpg\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/delito-de-acoso-sexual.jpg\",\"width\":1024,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venfort.com\\\/delito-de-acoso-sexual-mujeres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/venfort.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El delito de acoso sexual es un tema a atender por la justicia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#website\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"name\":\"Venfort\",\"description\":\"Firma de Abogados | Derecho Penal Econ\u00f3mico, Derecho Penal Internacional, Derecho de Empresas, Derecho Financiero, Derecho Administrativo, Derecho Civil y Sucesiones Internacionales\",\"publisher\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\"},\"alternateName\":\"VENFORT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venfort.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#organization\",\"name\":\"Venfort Abogados\",\"alternateName\":\"VENFORT\",\"url\":\"https:\\\/\\\/venfort.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"contentUrl\":\"https:\\\/\\\/venfort.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Venfort_Horizontal_Color.png\",\"width\":1000,\"height\":237,\"caption\":\"Venfort Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/venfortyabogados\",\"https:\\\/\\\/x.com\\\/Venfortabogados\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/venfort-aldana-abogados\",\"https:\\\/\\\/www.instagram.com\\\/venfortabogados\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/venfort.com\\\/#\\\/schema\\\/person\\\/6c0e1de9015eb56bbbf307df50c9872e\",\"name\":\"VENFORT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g\",\"caption\":\"VENFORT\"},\"url\":\"https:\\\/\\\/venfort.com\\\/fr\\\/author\\\/venfortadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le crime de harc\u00e8lement sexuel est une question qui doit \u00eatre trait\u00e9e par le syst\u00e8me judiciaire.","description":"Comment le crime de harc\u00e8lement sexuel est-il d\u00e9fini ? Dans cet article, nous souhaitons aborder cette question importante qui fait l'objet d'une conversation mondiale et qui est une question de justice en suspens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venfort.com\/fr\/infraction-de-harcelement-sexuel-des-femmes\/","og_locale":"fr_FR","og_type":"article","og_title":"El delito de acoso sexual es un tema a atender por la justicia","og_description":"\u00bfC\u00f3mo se define el delito de acoso sexual? En este art\u00edculo queremos abordar este importante tema que est\u00e1 en la conversaci\u00f3n mundial y que es un pendiente de la justicia.","og_url":"https:\/\/venfort.com\/fr\/infraction-de-harcelement-sexuel-des-femmes\/","og_site_name":"Venfort","article_publisher":"https:\/\/www.facebook.com\/venfortyabogados","article_published_time":"2018-02-15T12:00:35+00:00","og_image":[{"width":1024,"height":655,"url":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/02\/delito-de-acoso-sexual.jpg","type":"image\/jpeg"}],"author":"VENFORT","twitter_card":"summary_large_image","twitter_creator":"@Venfortabogados","twitter_site":"@Venfortabogados","twitter_misc":{"\u00c9crit par":"VENFORT","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#article","isPartOf":{"@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/"},"author":{"name":"VENFORT","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e"},"headline":"El delito de acoso sexual es un tema a atender por la justicia","datePublished":"2018-02-15T12:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/"},"wordCount":652,"publisher":{"@id":"https:\/\/venfort.com\/#organization"},"image":{"@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/02\/delito-de-acoso-sexual.jpg","keywords":["acoso sexual","Consideraciones Legales","Derechos Humanos"],"articleSection":["Ejercicio Profesional","Sin categor\u00eda"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/","url":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/","name":"Le crime de harc\u00e8lement sexuel est une question qui doit \u00eatre trait\u00e9e par le syst\u00e8me judiciaire.","isPartOf":{"@id":"https:\/\/venfort.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/02\/delito-de-acoso-sexual.jpg","datePublished":"2018-02-15T12:00:35+00:00","description":"Comment le crime de harc\u00e8lement sexuel est-il d\u00e9fini ? Dans cet article, nous souhaitons aborder cette question importante qui fait l'objet d'une conversation mondiale et qui est une question de justice en suspens.","breadcrumb":{"@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#primaryimage","url":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/02\/delito-de-acoso-sexual.jpg","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2018\/02\/delito-de-acoso-sexual.jpg","width":1024,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/venfort.com\/delito-de-acoso-sexual-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/venfort.com\/"},{"@type":"ListItem","position":2,"name":"El delito de acoso sexual es un tema a atender por la justicia"}]},{"@type":"WebSite","@id":"https:\/\/venfort.com\/#website","url":"https:\/\/venfort.com\/","name":"Venfort","description":"Cabinet : Droit p\u00e9nal \u00e9conomique, droit p\u00e9nal international, droit des soci\u00e9t\u00e9s, droit financier, droit administratif, droit civil et droit des successions internationales","publisher":{"@id":"https:\/\/venfort.com\/#organization"},"alternateName":"VENFORT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venfort.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/venfort.com\/#organization","name":"Avocats de Venfort","alternateName":"VENFORT","url":"https:\/\/venfort.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/","url":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","contentUrl":"https:\/\/venfort.com\/wp-content\/uploads\/2026\/03\/Logo_Venfort_Horizontal_Color.png","width":1000,"height":237,"caption":"Venfort Abogados"},"image":{"@id":"https:\/\/venfort.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/venfortyabogados","https:\/\/x.com\/Venfortabogados","https:\/\/www.linkedin.com\/company\/venfort-aldana-abogados","https:\/\/www.instagram.com\/venfortabogados"]},{"@type":"Person","@id":"https:\/\/venfort.com\/#\/schema\/person\/6c0e1de9015eb56bbbf307df50c9872e","name":"VENFORT","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4d96769bd368e8f15c4aec9dce5b759ea0d3a49ad69242757e358a4ec75eba02?s=96&d=mm&r=g","caption":"VENFORT"},"url":"https:\/\/venfort.com\/fr\/author\/venfortadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/comments?post=2720"}],"version-history":[{"count":0,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/posts\/2720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media\/2721"}],"wp:attachment":[{"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/media?parent=2720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/categories?post=2720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/venfort.com\/fr\/wp-json\/wp\/v2\/tags?post=2720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}